{"id":806,"date":"2025-01-17T11:37:11","date_gmt":"2025-01-17T11:37:11","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=806"},"modified":"2025-02-12T10:45:08","modified_gmt":"2025-02-12T10:45:08","slug":"psicologia-da-fonte","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/","title":{"rendered":"Psicologia das fontes: percep\u00e7\u00e3o e significado"},"content":{"rendered":"\n<p>A escolha da fonte n\u00e3o \u00e9 apenas uma quest\u00e3o est\u00e9tica \u2013 ela afeta diretamente a percep\u00e7\u00e3o da marca e as emo\u00e7\u00f5es dos consumidores. Um mesmo texto pode transmitir sensa\u00e7\u00f5es completamente diferentes dependendo do tipo de letra utilizado.<\/p>\n\n\n\n<p>Marcas ic\u00f4nicas como <strong>Coca-Cola, Google e Chanel<\/strong> utilizam fontes que refletem sua identidade e valores. Enquanto algumas fontes transmitem <strong>eleg\u00e2ncia e sofistica\u00e7\u00e3o<\/strong>, outras evocam <strong>modernidade e inova\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Neste artigo, exploramos como a psicologia das fontes influencia a percep\u00e7\u00e3o do p\u00fablico, quais estilos s\u00e3o mais eficazes para cada contexto e como escolher a melhor tipografia para seu projeto.<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2><b>Como as fontes influenciam a percep\u00e7\u00e3o emocional?<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Cientistas e psic\u00f3logos identificaram diversas categorias de fontes b\u00e1sicas com base na mudan\u00e7a de humor dos clientes ap\u00f3s as visualizarem.<\/span><\/p>\n\n\n\n<h3><b>Fonte alongada vertical<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133910\/open-sans.png\" alt=\"Open Sans \" class=\"wp-image-810\" title=\"Open Sans \" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133910\/open-sans.png\" data-full-size=\"1000x300\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa fonte \u00e9 uma op\u00e7\u00e3o vers\u00e1til para diversos tipos de neg\u00f3cios. No entanto, marcas que buscam se destacar podem precisar de um design mais original. Para evitar que o logotipo pare\u00e7a gen\u00e9rico, \u00e9 poss\u00edvel adicionar elementos coloridos ou personalizar detalhes tipogr\u00e1ficos.<\/span><\/p>\n\n\n\n<h3><b>Fonte quadrada formal<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133910\/furore.png\" alt=\"Furore \" class=\"wp-image-811\" title=\"Furore\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133910\/furore.png\" data-full-size=\"1000x300\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">Na maioria das vezes, esse tipo de fonte \u00e9 usado no design de letreiros promocionais de produtos industriais, bem como em diversos produtos tecnol\u00f3gicos e cartazes sociais. A fonte quadrada formal enfatizar\u00e1 a import\u00e2ncia dos dados e far\u00e1 as pessoas receberem as informa\u00e7\u00f5es promocionais com seriedade. Esse estilo tamb\u00e9m \u00e9 adequado para atrair a aten\u00e7\u00e3o de empres\u00e1rios para sua marca.<\/span><\/p>\n\n\n\n<h3><b>Fonte arredondada<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133910\/comfortaa.png\" alt=\"Comfortaa \" class=\"wp-image-812\" title=\"Comfortaa \" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133910\/comfortaa.png\" data-full-size=\"1000x300\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">As fontes desse tipo, quando empregadas em logotipos, trazem aos seus clientes um senso de conforto. Por outro lado, as fontes angulares tamb\u00e9m parecem muito formais. Um estilo de escrita com formas arredondadas \u00e9 notado por potenciais clientes como uma garantia do cuidado e da generosidade da empresa.<\/span><\/p>\n\n\n\n<h3><b>Fonte obl\u00edqua com vinhetas<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133909\/vegan-style-font.png\" alt=\"vegan style \" class=\"wp-image-813\" title=\"vegan style \" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133909\/vegan-style-font.png\" data-full-size=\"1000x300\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">Costuma ser usada na promo\u00e7\u00e3o de produtos com p\u00fablico-alvo feminino. Esse estilo de fonte \u00e9 reconhecido gra\u00e7as \u00e0 sua leveza e beleza, e promove associa\u00e7\u00f5es agrad\u00e1veis entre garotas e mulheres jovens. Voc\u00ea encontra esse estilo de fonte em an\u00fancios publicit\u00e1rios de sal\u00f5es de beleza, bem como em lojas de roupas femininas e embalagens de cosm\u00e9ticos. O uso do it\u00e1lico faz com que os clientes recebam as informa\u00e7\u00f5es com maior facilidade, j\u00e1 que elas parecem ser especialmente importantes. \u00c9 por isso as notas de rodap\u00e9 e observa\u00e7\u00f5es costumam ser escritas em it\u00e1lico.<\/span><\/p>\n\n\n\n<h3><b>Fonte manuscrita<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133909\/handwriten-font.png\" alt=\"Handwriten \" class=\"wp-image-814\" title=\"Handwriten \" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133909\/handwriten-font.png\" data-full-size=\"1000x300\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">Fontes manuscritas transmitem exclusividade e autenticidade, sendo amplamente utilizadas em marcas premium e identidades visuais sofisticadas. Embora sua legibilidade possa ser um desafio em outdoors ou banners grandes, o ajuste correto do tamanho e do espa\u00e7amento pode torn\u00e1-las eficazes para diversos formatos publicit\u00e1rios.<\/span><\/p>\n\n\n\n<h3><b>Fonte decorativa estilizada<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133908\/decorative-font.png\" alt=\"fonte decorativa\" class=\"wp-image-815\" title=\"fonte decorativa\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133908\/decorative-font.png\" data-full-size=\"1000x300\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">Esse tipo de fonte se assemelha \u00e0s escritas do estilo g\u00f3tico. Recomendamos que o aplique somente em situa\u00e7\u00f5es apropriadas. Por exemplo, ele n\u00e3o \u00e9 adequado para o letreiro de uma creche ou sal\u00e3o de beleza. Por outro lado, uma escrita estilizada ter\u00e1 um belo visual no letreiro de um bar tem\u00e1tico.<\/span><\/p>\n\n\n\n<h2><b>Exemplos de fontes populares<\/b><\/h2>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fontes com serifa: <\/b><i><span style=\"font-weight: 400;\">Baskerville, Didot, Garamond, Georgia, Times.<\/span><\/i><span style=\"font-weight: 400;\"> Essas fontes s\u00e3o vistas como tradicionais, pr\u00e1ticas e refinadas.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fontes sem serifa: <\/b><i><span style=\"font-weight: 400;\">Avenir, Futura, Gill Sans, Helvetica, Verdana.<\/span><\/i><span style=\"font-weight: 400;\"> Elas s\u00e3o caracterizadas por sua universalidade, modernidade, pureza e formas geom\u00e9tricas<\/span><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fontes manuscritas: <\/b><i><span style=\"font-weight: 400;\">Buttermilk, Edwardian, Isabella, Snell Roundhand, Zapfino<\/span><\/i><span style=\"font-weight: 400;\">. Essas fontes s\u00e3o associadas \u00e0 eleg\u00e2ncia, sofistica\u00e7\u00e3o e estilo.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fontes para bares: <\/b><i><span style=\"font-weight: 400;\">Clarendon, Copse, Josefin, Museo, Silverlake.<\/span><\/i><span style=\"font-weight: 400;\"> Elas incluem fontes modernas, extravagantes e amig\u00e1veis aos usu\u00e1rios.<\/span><\/li><\/ul>\n\n\n\n<h3><b>Fontes com serifa e sem serifa \u2013 qual \u00e9 a diferen\u00e7a?<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133907\/creative-logos-1.png\" alt=\"logotipos criativos\" class=\"wp-image-818\" title=\"logotipos criativos\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133907\/creative-logos-1.png\" data-full-size=\"1260x1005\" \/><\/figure>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Fontes com serifa <\/span><\/i><span style=\"font-weight: 400;\">s\u00e3o compreendidas com maior efici\u00eancia em textos de formato impresso. As serifas possibilitam o aumento do contraste entre as letras, diferenciando-as. Ao ler um texto digital escrito com esse tipo de fonte, fica dif\u00edcil tentar identificar letras individuais. \u00c9 por isso que a percep\u00e7\u00e3o da informa\u00e7\u00e3o por parte de um leitor n\u00e3o \u00e9 t\u00e3o eficiente<\/span><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p>\n\n\n\n<p><i><span style=\"font-weight: 400;\">Fontes sem serifa <\/span><\/i><span style=\"font-weight: 400;\">s\u00e3o ideais para textos publicados na internet. As letras desse estilo t\u00eam uma apar\u00eancia atrativa em elementos publicit\u00e1rios ao ar livre, preservando sua integridade at\u00e9 mesmo quando o tamanho da fonte \u00e9 aumentado para impress\u00e3o. Esse tipo de fonte atrai a aten\u00e7\u00e3o dos clientes e \u00e9 a melhor op\u00e7\u00e3o para textos pequenos. Mas recomendamos selecionar fontes com serifa como o estilo de escrita b\u00e1sico para textos longos, uma vez que elas n\u00e3o cansam o leitor t\u00e3o rapidamente.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Estat\u00edsticas apontam que as fontes do primeiro tipo s\u00e3o usadas no t\u00edtulo de textos em 40% dos casos. Em contrapartida, mais de 60% dos sites preferem fontes sem serifa no corpo de seus textos.<\/span><\/p>\n\n\n\n<h3><b>Alguns aspectos da percep\u00e7\u00e3o de fontes em logotipos<\/b><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133907\/brand-names-fonts.jpg\" alt=\"Fontes de nomes de marcas\" class=\"wp-image-817\" title=\"Fontes de nomes de marcas\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133907\/brand-names-fonts.jpg\" data-full-size=\"1138x640\" \/><\/figure>\n\n\n\n<p><span style=\"font-weight: 400;\">Apenas 6% dos logotipos de marcas internacionais usam um \u00edcone. 56% dos criadores de logotipos aplicam uma combina\u00e7\u00e3o de textos e imagens e os 37% restantes preferem usar somente escrita. Isso comprova que empresas est\u00e3o acostumadas a usar o texto como o principal elemento de sua marca. A sele\u00e7\u00e3o de uma fonte adequada \u00e9 essencial para assegurar o futuro sucesso de uma empresa. Ela \u00e9 necess\u00e1ria para fazer com que os clientes sintam a ess\u00eancia da marca e as caracter\u00edsticas dos produtos oferecidos.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Os logotipos que aplicam texto dentro de um <\/span><i><span style=\"font-weight: 400;\">c\u00edrculo <\/span><\/i><span style=\"font-weight: 400;\">ou <\/span><i><span style=\"font-weight: 400;\">quadrado <\/span><\/i><span style=\"font-weight: 400;\">transmitem a impress\u00e3o geral da confian\u00e7a e seguran\u00e7a da empresa aos clientes. Se ao inv\u00e9s dessas figuras voc\u00ea opta por uma <\/span><i><span style=\"font-weight: 400;\">elipse,<\/span><\/i><span style=\"font-weight: 400;\"> a marca ser\u00e1 associada \u00e0 criatividade. Um texto dentro de um <\/span><i><span style=\"font-weight: 400;\">tri\u00e2ngulo invertido <\/span><\/i><span style=\"font-weight: 400;\">\u00e9 visto como uma solicita\u00e7\u00e3o de tomada de a\u00e7\u00e3o (<\/span><i><span style=\"font-weight: 400;\">call to action<\/span><\/i><span style=\"font-weight: 400;\">). Se o nome da empresa estiver disposto <\/span><i><span style=\"font-weight: 400;\">diagonalmente, <\/span><\/i><span style=\"font-weight: 400;\">o logotipo faz as pessoas acreditarem que a organiza\u00e7\u00e3o oferece vantagens especiais, que incluem alta velocidade e confiabilidade.<\/span><\/p>\n\n\n\n<h2><b>A fonte que \u00e9 melhor compreendida pelos clientes<\/b><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Em mais de 60% dos casos, fontes sem serifa s\u00e3o utilizadas no design de logotipos devido \u00e0 sua legibilidade e modernidade. A Helvetica \u00e9 uma das mais populares, presente em marcas como Saint Laurent, HBA e Comme des Gar\u00e7ons. Outras fontes igualmente eficazes incluem Futura, Arial e Montserrat, que oferecem um equil\u00edbrio entre eleg\u00e2ncia e clareza.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133908\/helvetica.jpg\" alt=\"helvetica neue\" class=\"wp-image-816\" title=\"helvetica neue\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133908\/helvetica.jpg\" data-full-size=\"1120x600\" \/><\/figure>\n\n\n\n<h3><b>Orienta\u00e7\u00f5es para sele\u00e7\u00e3o de fontes<\/b><\/h3>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fontes grandes e em negrito s\u00e3o perfeitas para publicidade ao ar livre, pois s\u00e3o leg\u00edveis em fundos de qualquer cor e reconhecidas com muita facilidade. Voc\u00ea deve considerar a dist\u00e2ncia ao posicionar um logotipo. Se for de cerca de cinco metros, deve escolher letras com mais de 5 cm de altura.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Se poss\u00edvel, n\u00e3o use mais de tr\u00eas estilos de fontes diferentes em um banner, para n\u00e3o dificultar demais a recep\u00e7\u00e3o das informa\u00e7\u00f5es.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O tamanho deve ser de 11-12 pontos caso seu p\u00fablico-alvo inclua a popula\u00e7\u00e3o em geral. \u00c9 melhor usar um letreiro com uma fonte de pelo menos 18 pontos para clientes potenciais com mais de 60 anos. O t\u00edtulo do texto deve ter entre 14-30 pontos.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">N\u00e3o escreva seu texto com letras mai\u00fasculas, pois elas dificultam a leitura. Se o fundo for brilhante, voc\u00ea precisa evitar letras ornamentadas.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fontes com serifa s\u00e3o adequadas para materiais promocionais impressos, pois cada letra ser\u00e1 percebida separadamente.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Alterar o tamanho da linha possibilita que voc\u00ea controle a velocidade de leitura. Para melhorar a qualidade da transmiss\u00e3o das informa\u00e7\u00f5es, recomendamos levar em conta o espa\u00e7amento entre letras e linhas.<\/span><\/li><\/ul>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-1740\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/design-de-logotipo-eficaz\/\">O que torna um design de logotipo eficaz<\/a><\/li>\n<li id=\"su-post-9545\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-da-unilever\/\">O logotipo da Unilever: Hist\u00f3ria e significado<\/a><\/li>\n<li id=\"su-post-9302\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipos-brancos\/\">Logotipos brancos: Significado e melhores exemplos de logotipos<\/a><\/li>\n<li id=\"su-post-9207\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logos-azuis\/\">Logos azuis: significado e exemplos<\/a><\/li>\n<li id=\"su-post-10634\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/gerador-design-ia-criativos-fotos-ia\/\">Como criar criativos publicit\u00e1rios e sess\u00f5es de fotos com IA usando um gerador de design<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A escolha da fonte n\u00e3o \u00e9 apenas uma quest\u00e3o est\u00e9tica \u2013 ela afeta diretamente a percep\u00e7\u00e3o da marca e as&#8230;<\/p>\n","protected":false},"author":1,"featured_media":820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Psicologia das fontes: percep\u00e7\u00e3o e significado | Turbologo<\/title>\n<meta name=\"description\" content=\"Como escolher uma fonte que pode lhe trazer mais clientes? A psicologia das fontes o ajudar\u00e1 a encontrar as fontes certas para um logotipo legal. Neste artigo, a Turbologo est\u00e1 dizendo que tipo de fonte atrairia mais seus clientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Psicologia das fontes: percep\u00e7\u00e3o e significado | Turbologo\" \/>\n<meta property=\"og:description\" content=\"Como escolher uma fonte que pode lhe trazer mais clientes? A psicologia das fontes o ajudar\u00e1 a encontrar as fontes certas para um logotipo legal. Neste artigo, a Turbologo est\u00e1 dizendo que tipo de fonte atrairia mais seus clientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T11:37:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-12T10:45:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133906\/psihologia-shriftov.png\" \/>\n\t<meta property=\"og:image:width\" content=\"778\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Ilya Lavrov\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"5 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/04\/19133906\/psihologia-shriftov.png\",\"width\":778,\"height\":555,\"caption\":\"Psicologia de fontes\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/\",\"name\":\"Psicologia das fontes: percep\\u00e7\\u00e3o e significado | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#primaryimage\"},\"datePublished\":\"2025-01-17T11:37:11+00:00\",\"dateModified\":\"2025-02-12T10:45:08+00:00\",\"description\":\"Como escolher uma fonte que pode lhe trazer mais clientes? A psicologia das fontes o ajudar\\u00e1 a encontrar as fontes certas para um logotipo legal. Neste artigo, a Turbologo est\\u00e1 dizendo que tipo de fonte atrairia mais seus clientes.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/\",\"name\":\"Psicologia das fontes: percep\\u00e7\\u00e3o e significado\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/379800fa881357672b0119e4a2994c17\"},\"headline\":\"Psicologia das fontes: percep\\u00e7\\u00e3o e significado\",\"datePublished\":\"2025-01-17T11:37:11+00:00\",\"dateModified\":\"2025-02-12T10:45:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#primaryimage\"},\"articleSection\":\"Marketing\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/psicologia-da-fonte\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/379800fa881357672b0119e4a2994c17\",\"name\":\"Ilya Lavrov\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/713d4593fdd72be34274409471435888?s=96&d=mm&r=g\",\"caption\":\"Ilya Lavrov\"},\"description\":\"Sou designer de produto e gr\\u00e1fico com 10 anos de experi\\u00eancia. Escrever sobre branding, cria\\u00e7\\u00e3o de logotipos e neg\\u00f3cios.\",\"sameAs\":[\"http:\/\/ilyalavrov.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/806"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=806"}],"version-history":[{"count":15,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/806\/revisions"}],"predecessor-version":[{"id":10357,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/806\/revisions\/10357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/820"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}