{"id":1779,"date":"2021-05-07T04:19:07","date_gmt":"2021-05-07T04:19:07","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=1779"},"modified":"2022-03-15T07:24:52","modified_gmt":"2022-03-15T07:24:52","slug":"taco-bell-logo","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/","title":{"rendered":"Significado do Logotipo Taco Bell &#8211; Hist\u00f3ria e Evolu\u00e7\u00e3o"},"content":{"rendered":"\n<p>A Taco Bell \u00e9 um dos maiores players do mercado de fast-food. A escala de atividade da empresa \u00e9 dif\u00edcil de avaliar no in\u00edcio, pois seus comensais podem n\u00e3o ser os mais brilhantes. Entretanto, a <a href=\"https:\/\/turbologo.com\/pt\/blog\/design-do-logotipo-da-empresa\/\">empresa<\/a> emprega 20.000 funcion\u00e1rios por ano. Como eles conseguem manter o crescimento? O que est\u00e1 por tr\u00e1s daquele logotipo comum da Taco Bell? Vamos descobrir!<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2>O in\u00edcio do sucesso<\/h2>\n\n\n\n<p>A quest\u00e3o \u00e9: por que escolheram um nome pouco relacionado a alimentos? E com o que come\u00e7ou a hist\u00f3ria do logotipo da Taco Bell? Para obter as respostas, estamos obrigados a ir para o passado. Tudo mudou ap\u00f3s a Segunda Guerra Mundial. Muitas pessoas foram redigidas e depois dispensadas. Como resultado, elas foram completamente detidas de suas ocupa\u00e7\u00f5es anteriores. Muitas f\u00e1bricas foram for\u00e7adas a redirecionar seus vetores de desenvolvimento para objetivos mais pac\u00edficos. As pessoas tinham que buscar formas pac\u00edficas de ganhar a vida. Glen Bell, um fuzileiro naval, tamb\u00e9m enfrentou o mesmo destino. Como voc\u00ea j\u00e1 deve ter adivinhado, ele fundou a empresa. E isso explica o sino no logotipo. E seu sobrenome ainda apresenta o logotipo da Taco Bell.<\/p>\n\n\n\n<p>O mercado de alimentos dos anos 50 poderia listar muitos dos que hoje em dia s\u00e3o gigantes do fast food. O <a href=\"https:\/\/turbologo.com\/pt\/blog\/mcdonalds-logo\/\">McDonald&#8217;s<\/a> \u00e9 provavelmente o melhor exemplo aqui. \u00c9 por isso que outra loja de hamb\u00fargueres certamente iria falhar. Glenn costumava passear por uma cidade em busca de uma id\u00e9ia nova em folha. E finalmente, ele teve a sorte de notar longas filas de espera nas portas dos <a href=\"https:\/\/turbologo.com\/pt\/blog\/restaurante-logo\/\">restaurantes<\/a> mexicanos. Esse tipo de comida era uma vis\u00e3o rara naqueles dias e os restaurantes estavam obtendo um bom pre\u00e7o por ela.<\/p>\n\n\n\n<h2>A primeira cria\u00e7\u00e3o do logotipo da Taco Bell<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2020\/02\/Taco-Bell-first-logo.png\" alt=\"Primeiro logotipo da Taco Bell\" class=\"wp-image-1843\" title=\"Primeiro logotipo da Taco Bell\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133325\/Taco-Bell-first-logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133325\/Taco-Bell-first-logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133325\/Taco-Bell-first-logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133325\/Taco-Bell-first-logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>Glen come\u00e7ou a construir um restaurante ao estilo mexicano assim que percebeu que nachos e burritos o tornariam rico. O antigo logotipo da Taco Bell era composto pelas cores da bandeira do M\u00e9xico. O logotipo foi criado na d\u00e9cada de 60, mas a <a href=\"https:\/\/turbologo.com\/pt\/blog\/combinacoes-de-cores\/\">combina\u00e7\u00e3o de cores<\/a> ainda \u00e9 deliciosa. Todas as cores s\u00e3o as mais adequadas para restaurantes de fast food. Por que isso \u00e9 assim? Bem, \u00e9 um conhecimento comum, na verdade. Amarelo significa \u00f3leo quente, e verde \u00e9 para verduras frescas e pimenta picante. E o vermelho simboliza uma carne apetitosa com p\u00e1prica quente. Com certeza fez \u00e1gua na boca, n\u00e3o \u00e9 mesmo?<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Deseja fazer seu pr\u00f3prio logotipo de restaurante? Explore as <a href=\"https:\/\/turbologo.com\/pt\/ideias-para-logotipos\/restaurante\">id\u00e9ias de design de logotipos de restaurantes<\/a> em nossa galeria.<\/pre>\n\n\n\n<p>Talvez a Taco Bell tenha ficado famosa devido \u00e0 falta de rivais, mas o logotipo certamente tem algo a ver com isso tamb\u00e9m. A representa\u00e7\u00e3o parece mon\u00f3tona hoje em dia, mas costumava atrair milhares de clientes. E a antiga <a href=\"https:\/\/turbologo.com\/pt\/blog\/escolhendo-a-fonte-do-logotipo\/\">fonte do logotipo<\/a> da Taco Bell se parece muito com Macbeth. As identidades gerais tamb\u00e9m se mostraram bem equilibradas.<\/p>\n\n\n\n<h2>Novo logotipo e rebranding da Taco Bell<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2020\/02\/Taco-Bell-logo-history.png\" alt=\"Hist\u00f3ria do logotipo da Taco Bell\" class=\"wp-image-1844\" title=\"Hist\u00f3ria do logotipo da Taco Bell\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo-history.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo-history-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo-history-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo-history.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>Eles perceberam que os anos 90 s\u00e3o lugar para coisas atualizadas e que est\u00e1 na hora de criar algo novo. Eles tamb\u00e9m decidiram manter o significado do logotipo da Taco Bell. Ele ainda representava o sobrenome do fundador. No entanto, as cores e a fonte foram alteradas. Uma nova imagem \u00e9 muito melhor do que a antiga. Em particular, tornou-se mais din\u00e2mica, o sino est\u00e1 quase tocando, pois atrai novos clientes. No entanto, a altera\u00e7\u00e3o de cores n\u00e3o foi a mais plaus\u00edvel. A empresa decidiu adotar as cores f\u00facsia \u00e1cido-rosado, violeta e amarelo para se diferenciar das rivais. E n\u00e3o \u00e9 a melhor solu\u00e7\u00e3o aqui. Quanto a uma nova fonte do logotipo da Taco Bell, eles escolheram a Helvetica.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2020\/02\/Taco-Bell-logo.png\" alt=\"Logotipo da Taco Bell\" class=\"wp-image-1845\" title=\"Logotipo da Taco Bell\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133324\/Taco-Bell-logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\">Procurando por logotipo de alimentos? Explore as <a href=\"https:\/\/turbologo.com\/pt\/ideias-para-logotipos\/3-comida\">id\u00e9ias de design de logotipos de alimentos<\/a> em nossa galeria.<\/pre>\n\n\n\n<p>E at\u00e9 mesmo o novo logotipo foi ligeiramente alterado em 2016. No entanto, os clientes n\u00e3o gostaram muito. A fonte foi alterada para Akzidenz-Grotesk e se assemelha claramente \u00e0 Helvetica. Estranhamente, mas eles removeram toda a din\u00e2mica. No entanto, o grande problema s\u00e3o as cores. O violeta sujo \u00e9 uma cor importante agora. \u00c9 dif\u00edcil imaginar uma cor ainda menos apetitosa. Parece que todas as cores frias s\u00e3o tabu para a ind\u00fastria aliment\u00edcia. As tonalidades s\u00e3o melhor usadas em lojas de produtos qu\u00edmicos, pois lembram a agress\u00e3o do frio.<\/p>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1647329021356\"><strong class=\"schema-faq-question\">Quem criou o logotipo da Taco Bell?<\/strong> <p class=\"schema-faq-answer\">A Taco Bell apresentou um novo logotipo minimalista em 14 de novembro de 2016 e foi criado em colabora\u00e7\u00e3o com a ag\u00eancia nova-iorquina Lippincott e o grupo de design interno da Taco Bell. H\u00e1 um logotipo em forma roxa com um sino branco, e sob o formato h\u00e1 as palavras Taco e Bell em texto preto. A flexibilidade do novo design permite que os propriet\u00e1rios o personalizem de acordo com suas prefer\u00eancias. A estrat\u00e9gia de rebranding relevante deu um segundo vento ao desenvolvimento do neg\u00f3cio da Taco Bell.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329034577\"><strong class=\"schema-faq-question\">Qual \u00e9 o segredo do sucesso da Taco Bell?<\/strong> <p class=\"schema-faq-answer\">A empresa cresceu em popularidade t\u00e3o rapidamente que em cinco anos j\u00e1 contava com 100 restaurantes e em oito anos ap\u00f3s o seu in\u00edcio, tinha 325 restaurantes p\u00fablicos. O fato de terem introduzido o card\u00e1pio de valores onde tinham uma grande variedade de 0,59, 0,79 e 0,99 centavos de d\u00f3lar, influenciou para melhor. A disponibilidade e um pre\u00e7o acess\u00edvel da apetitosa comida mexicana foram os fatores-chave para o sucesso. Tudo o que era necess\u00e1rio era dar a um cliente o que ele queria e nada mais. A comida saborosa como pizza, nachos, tacos de casca macia que \u00e9 r\u00e1pida e barata levou a empresa a lucros hist\u00f3ricos.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329041829\"><strong class=\"schema-faq-question\">Por que uma campainha?<\/strong> <p class=\"schema-faq-answer\">A forma do sino foi especificamente direcionada, pois indica o sobrenome do fundador da empresa e tem o nome de Glen Bell. Entre outras coisas, o som festivo do sino simboliza a \u00e9poca das f\u00e9rias e tamb\u00e9m atrai um fluxo de novos clientes. Acredita-se tamb\u00e9m que o espa\u00e7o dentro do sino, em particular o cortador \u00e9 semelhante ao formato de um taco. A empresa \u00e9 famosa pelos tacos e tortilhas, portanto, a escolha reflete diretamente os elementos do prato principal.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329051862\"><strong class=\"schema-faq-question\">Por que o logotipo da Taco Bell est\u00e1 nestas cores?<\/strong> <p class=\"schema-faq-answer\">Como a empresa prefere se manter moderna e permanecer na demanda, ela deve atender \u00e0s exig\u00eancias das solu\u00e7\u00f5es de estilo de design moderno. As cores vibrantes roxo claro e escuro, preto e branco significam originalidade e estilo irrepet\u00edvel. O logotipo tornou-se mais \u00fanico, limpo e lac\u00f4nico e agora est\u00e1 em linha com a Metal Aesthetics. A empresa criou uma nova identidade para sua marca, simplificando a logomarca e tornando-a mais vers\u00e1til. Considera-se que a presen\u00e7a das cores rosa, amarelo e roxo juntas dificulta imediatamente a coloca\u00e7\u00e3o de banners com o logotipo sobre um fundo escuro ou colorido. De acordo com outra vis\u00e3o, a cor roxa simboliza o luxo e acrescenta uma verdadeira sofistica\u00e7\u00e3o ao gosto.<\/p> <\/div> <\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-1079\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/walmart-logo\/\">A hist\u00f3ria do Walmart e seu design de logotipo<\/a><\/li>\n<li id=\"su-post-9551\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-guinness\/\">Logotipo Guinness: Hist\u00f3ria e Significado<\/a><\/li>\n<li id=\"su-post-9447\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-do-playstation\/\">A evolu\u00e7\u00e3o do logotipo do PlayStation: hist\u00f3ria e significado<\/a><\/li>\n<li id=\"su-post-9724\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/design-do-logotipo-fortnite\/\">Design do logotipo Fortnite &#8211; Hist\u00f3ria, significado e evolu\u00e7\u00e3o<\/a><\/li>\n<li id=\"su-post-1071\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\">A evolu\u00e7\u00e3o e a hist\u00f3ria do logotipo da Instagram<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Taco Bell \u00e9 um dos maiores players do mercado de fast-food. A escala de atividade da empresa \u00e9 dif\u00edcil&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Significado do Logotipo Taco Bell - Hist\u00f3ria e Evolu\u00e7\u00e3o | Turbologo<\/title>\n<meta name=\"description\" content=\"A hist\u00f3ria do logotipo da Taco Bell come\u00e7a ap\u00f3s a Segunda Guerra Mundial. O novo logotipo da Taco Bell foi projetado na d\u00e9cada de 90.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Significado do Logotipo Taco Bell - Hist\u00f3ria e Evolu\u00e7\u00e3o | Turbologo\" \/>\n<meta property=\"og:description\" content=\"A hist\u00f3ria do logotipo da Taco Bell come\u00e7a ap\u00f3s a Segunda Guerra Mundial. O novo logotipo da Taco Bell foi projetado na d\u00e9cada de 90.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T04:19:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T07:24:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133323\/Taco-Bell.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Victoria Maybach\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"5 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/02\/19133323\/Taco-Bell.png\",\"width\":1024,\"height\":600,\"caption\":\"Taco Bell\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/\",\"name\":\"Significado do Logotipo Taco Bell - Hist\\u00f3ria e Evolu\\u00e7\\u00e3o | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#primaryimage\"},\"datePublished\":\"2021-05-07T04:19:07+00:00\",\"dateModified\":\"2022-03-15T07:24:52+00:00\",\"description\":\"A hist\\u00f3ria do logotipo da Taco Bell come\\u00e7a ap\\u00f3s a Segunda Guerra Mundial. O novo logotipo da Taco Bell foi projetado na d\\u00e9cada de 90.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/\",\"name\":\"Significado do Logotipo Taco Bell &#8211; Hist\\u00f3ria e Evolu\\u00e7\\u00e3o\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\"},\"headline\":\"Significado do Logotipo Taco Bell &#8211; Hist\\u00f3ria e Evolu\\u00e7\\u00e3o\",\"datePublished\":\"2021-05-07T04:19:07+00:00\",\"dateModified\":\"2022-03-15T07:24:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#primaryimage\"},\"articleSection\":\"Branding\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\",\"name\":\"Victoria Maybach\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/227e182dfb1b824e5a150c453121a92b?s=96&d=mm&r=g\",\"caption\":\"Victoria Maybach\"},\"description\":\"Editor de blogs e especialista em marketing de conte\\u00fado da Turbologo. Escrevendo sobre marketing e design. Os artigos de Victoria cont\\u00eam dicas \\u00fateis sobre como construir uma marca e promov\\u00ea-la online.\"},{\"@type\":\"ItemList\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#article\"},\"numberOfItems\":4,\"itemListElement\":[{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329021356\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329034577\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329041829\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329051862\"}]},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329021356\",\"position\":1,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329021356\",\"name\":\"Quem criou o logotipo da Taco Bell?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A Taco Bell apresentou um novo logotipo minimalista em 14 de novembro de 2016 e foi criado em colabora\\u00e7\\u00e3o com a ag\\u00eancia nova-iorquina Lippincott e o grupo de design interno da Taco Bell. H\\u00e1 um logotipo em forma roxa com um sino branco, e sob o formato h\\u00e1 as palavras Taco e Bell em texto preto. A flexibilidade do novo design permite que os propriet\\u00e1rios o personalizem de acordo com suas prefer\\u00eancias. A estrat\\u00e9gia de rebranding relevante deu um segundo vento ao desenvolvimento do neg\\u00f3cio da Taco Bell.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329034577\",\"position\":2,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329034577\",\"name\":\"Qual \\u00e9 o segredo do sucesso da Taco Bell?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A empresa cresceu em popularidade t\\u00e3o rapidamente que em cinco anos j\\u00e1 contava com 100 restaurantes e em oito anos ap\\u00f3s o seu in\\u00edcio, tinha 325 restaurantes p\\u00fablicos. O fato de terem introduzido o card\\u00e1pio de valores onde tinham uma grande variedade de 0,59, 0,79 e 0,99 centavos de d\\u00f3lar, influenciou para melhor. A disponibilidade e um pre\\u00e7o acess\\u00edvel da apetitosa comida mexicana foram os fatores-chave para o sucesso. Tudo o que era necess\\u00e1rio era dar a um cliente o que ele queria e nada mais. A comida saborosa como pizza, nachos, tacos de casca macia que \\u00e9 r\\u00e1pida e barata levou a empresa a lucros hist\\u00f3ricos.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329041829\",\"position\":3,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329041829\",\"name\":\"Por que uma campainha?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A forma do sino foi especificamente direcionada, pois indica o sobrenome do fundador da empresa e tem o nome de Glen Bell. Entre outras coisas, o som festivo do sino simboliza a \\u00e9poca das f\\u00e9rias e tamb\\u00e9m atrai um fluxo de novos clientes. Acredita-se tamb\\u00e9m que o espa\\u00e7o dentro do sino, em particular o cortador \\u00e9 semelhante ao formato de um taco. A empresa \\u00e9 famosa pelos tacos e tortilhas, portanto, a escolha reflete diretamente os elementos do prato principal.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329051862\",\"position\":4,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/taco-bell-logo\/#faq-question-1647329051862\",\"name\":\"Por que o logotipo da Taco Bell est\\u00e1 nestas cores?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Como a empresa prefere se manter moderna e permanecer na demanda, ela deve atender \\u00e0s exig\\u00eancias das solu\\u00e7\\u00f5es de estilo de design moderno. As cores vibrantes roxo claro e escuro, preto e branco significam originalidade e estilo irrepet\\u00edvel. O logotipo tornou-se mais \\u00fanico, limpo e lac\\u00f4nico e agora est\\u00e1 em linha com a Metal Aesthetics. A empresa criou uma nova identidade para sua marca, simplificando a logomarca e tornando-a mais vers\\u00e1til. Considera-se que a presen\\u00e7a das cores rosa, amarelo e roxo juntas dificulta imediatamente a coloca\\u00e7\\u00e3o de banners com o logotipo sobre um fundo escuro ou colorido. De acordo com outra vis\\u00e3o, a cor roxa simboliza o luxo e acrescenta uma verdadeira sofistica\\u00e7\\u00e3o ao gosto.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1779"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=1779"}],"version-history":[{"count":7,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1779\/revisions"}],"predecessor-version":[{"id":9808,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1779\/revisions\/9808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/1846"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=1779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=1779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=1779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}