{"id":1748,"date":"2021-05-07T04:52:29","date_gmt":"2021-05-07T04:52:29","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=1748"},"modified":"2021-05-07T05:22:15","modified_gmt":"2021-05-07T05:22:15","slug":"logotipo-responsivo","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/","title":{"rendered":"Como fazer um logotipo responsivo"},"content":{"rendered":"\n<p>As empresas n\u00e3o pareciam se importar com a adaptabilidade do r\u00f3tulo quando n\u00e3o havia internet. Eles estavam simplesmente fazendo an\u00fancios de TV e colocando o r\u00f3tulo em pacotes e caixas. Os tempos mudam e agora temos internet, smartphones e tablets. Seu logotipo pode ficar bem em um outdoor enorme, mas \u00e9 improv\u00e1vel que funcione como um favicon ou um \u00edcone em um site. Muitas empresas n\u00e3o percebem que o logotipo deve ser responsivo. Na maioria dos casos, os logotipos apenas ficam menores na web e perdem todos os recursos para os quais foram projetados. E se a <a href=\"https:\/\/turbologo.com\/pt\/blog\/identidade-corporativa\/\">identidade da marca<\/a> n\u00e3o for mais reconhecida, \u00e9 completamente in\u00fatil. \u00c9 por isso que vamos dizer a voc\u00ea como criar o melhor logotipo responsivo no artigo de hoje.<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2>Conceitos b\u00e1sicos de cria\u00e7\u00e3o de design responsivo<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2020\/06\/responsive_pnr.png\" alt=\"logotipos responsivos\" class=\"wp-image-6896\" width=\"590\" height=\"393\" title=\"logotipos responsivos\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133135\/responsive_pnr.png 580w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133135\/responsive_pnr-300x200.png 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133135\/responsive_pnr.png\" data-full-size=\"580x386\" \/><\/figure>\n\n\n\n<p>Em primeiro lugar, voc\u00ea ter\u00e1 que pesquisar seu estilo e identidade. Em seguida, voc\u00ea deve projetar algumas varia\u00e7\u00f5es desses, tendo em mente que as varia\u00e7\u00f5es devem ser usadas para diferentes prop\u00f3sitos, \u00e9 claro. Eles podem ser variados em termos de escala e orienta\u00e7\u00e3o. A primeira coisa \u00e9 bastante \u00f3bvia e a segunda n\u00e3o. A orienta\u00e7\u00e3o pode ser retrato e paisagem, e voc\u00ea vai precisar de ambas. Basicamente, voc\u00ea ter\u00e1 que alterar o local da inscri\u00e7\u00e3o e \u00e9 isso. E n\u00e3o se esque\u00e7a de projetar uma varia\u00e7\u00e3o quadrada tamb\u00e9m.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2020\/06\/7.png\" alt=\"logotipos responsivos\" class=\"wp-image-6893\" width=\"588\" height=\"430\" title=\"logotipos responsivos\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133136\/7.png 640w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133136\/7-300x219.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133136\/7-80x60.png 80w\" sizes=\"(max-width: 588px) 100vw, 588px\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133136\/7.png\" data-full-size=\"640x468\" \/><\/figure>\n\n\n\n<p>Agora que criamos duas orienta\u00e7\u00f5es, podemos prosseguir para como fazer um dimensionamento de logotipo responsivo. \u00c9 melhor que haja tr\u00eas vers\u00f5es, mas quatro \u00e9 a melhor. Certifique-se de definir prioridades para todas as inscri\u00e7\u00f5es, incluindo o slogan. A quantidade de texto deve ser reduzida de acordo com a diminui\u00e7\u00e3o da imagem. Al\u00e9m disso, n\u00e3o se esque\u00e7a de manter o tamanho da <a href=\"https:\/\/turbologo.com\/pt\/blog\/104-fontes-gratis-para-design-de-logotipo\/\">fonte<\/a> proporcional. E a menor vers\u00e3o do logotipo requer apenas iniciais e nada mais.<\/p>\n\n\n\n<p>Proceda de coisas compostas para coisas simples enquanto faz diferentes vers\u00f5es de logotipo. Diminua o n\u00famero de detalhes se um logotipo ficar menor. \u00c9 melhor reduzir gradientes multicoloridos para dois ou tr\u00eas gradientes coloridos. Desenhe uma linha em negrito em vez de duas mais finas. Al\u00e9m disso, unifique pequenos pol\u00edgonos evitando modifica\u00e7\u00f5es gerais na <a href=\"https:\/\/turbologo.com\/pt\/blog\/formas-de-logotipo\/\">forma do logotipo<\/a>.<\/p>\n\n\n\n<h2>Exemplos dos melhores logotipos responsivos<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"604\" height=\"428\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2020\/06\/adaptivnye-logotipy-primery-i-sposoby-adaptatsii5.jpg\" alt=\"logotipos responsivos Google Walt Disnay\" class=\"wp-image-6895\" title=\"logotipos responsivos Google Walt Disnay\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133135\/adaptivnye-logotipy-primery-i-sposoby-adaptatsii5.jpg 604w, https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133135\/adaptivnye-logotipy-primery-i-sposoby-adaptatsii5-300x213.jpg 300w\" sizes=\"(max-width: 604px) 100vw, 604px\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133135\/adaptivnye-logotipy-primery-i-sposoby-adaptatsii5.jpg\" data-full-size=\"604x428\" \/><\/figure>\n\n\n\n<p>Provavelmente, o melhor exemplo aqui \u00e9 a Walt Disney Company. A vers\u00e3o completa apresenta um castelo detalhado. Um reduzido representa apenas uma palavra. E o m\u00ednimo um nada mais \u00e9 do que uma \u00fanica letra inicial. No entanto, cada vers\u00e3o \u00e9 bem conhecida e reconhecida por todos. Channel, Warner Brothers, Levi\u2019s e Heineken s\u00e3o outros exemplos brilhantes. Se voc\u00ea tiver d\u00favidas sobre como <a href=\"https:\/\/turbologo.com\/pt\/criar-logo\">fazer um logotipo responsivo<\/a>, examine esses exemplos. Assim, voc\u00ea ser\u00e1 capaz de compreender os conceitos b\u00e1sicos de redu\u00e7\u00e3o consecutiva e laconismo.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-1075\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/amazon-logo\/\">A hist\u00f3ria da Amaz\u00f4nia e seu design de logotipo<\/a><\/li>\n<li id=\"su-post-9478\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/top-20-dos-logotipos-de-super-herois\/\">Top 20 dos logotipos de super-her\u00f3is mais famosos do mundo<\/a><\/li>\n<li id=\"su-post-832\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/104-fontes-gratis-para-design-de-logotipo\/\">104 fontes gratuitas perfeitas para design de logotipos<\/a><\/li>\n<li id=\"su-post-1870\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-da-coruja\/\">Logotipo da Owls: Como projetar online<\/a><\/li>\n<li id=\"su-post-1855\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/melhores-cores-para-logotipos\/\">Melhores cores para logotipos<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>As empresas n\u00e3o pareciam se importar com a adaptabilidade do r\u00f3tulo quando n\u00e3o havia internet. Eles estavam simplesmente fazendo an\u00fancios&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como fazer um logotipo responsivo | Turbologo<\/title>\n<meta name=\"description\" content=\"O melhor conselho sobre como fazer um logotipo responsivo \u00e9 que voc\u00ea crie cerca de tr\u00eas ou quatro varia\u00e7\u00f5es de logotipo. E eles servir\u00e3o a prop\u00f3sitos diferentes, \u00e9 claro. Google, Channel ou Heineken podem ostentar um dos melhores logotipos responsivos at\u00e9 agora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como fazer um logotipo responsivo | Turbologo\" \/>\n<meta property=\"og:description\" content=\"O melhor conselho sobre como fazer um logotipo responsivo \u00e9 que voc\u00ea crie cerca de tr\u00eas ou quatro varia\u00e7\u00f5es de logotipo. E eles servir\u00e3o a prop\u00f3sitos diferentes, \u00e9 claro. Google, Channel ou Heineken podem ostentar um dos melhores logotipos responsivos at\u00e9 agora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T04:52:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T05:22:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133136\/adaptivnye-logotipy-primery-i-sposoby-adaptatsii1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"604\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Ilya Lavrov\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/06\/19133136\/adaptivnye-logotipy-primery-i-sposoby-adaptatsii1.jpg\",\"width\":604,\"height\":376,\"caption\":\"Logotipo Responsivo\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/\",\"name\":\"Como fazer um logotipo responsivo | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#primaryimage\"},\"datePublished\":\"2021-05-07T04:52:29+00:00\",\"dateModified\":\"2021-05-07T05:22:15+00:00\",\"description\":\"O melhor conselho sobre como fazer um logotipo responsivo \\u00e9 que voc\\u00ea crie cerca de tr\\u00eas ou quatro varia\\u00e7\\u00f5es de logotipo. E eles servir\\u00e3o a prop\\u00f3sitos diferentes, \\u00e9 claro. Google, Channel ou Heineken podem ostentar um dos melhores logotipos responsivos at\\u00e9 agora.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/\",\"name\":\"Como fazer um logotipo responsivo\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/379800fa881357672b0119e4a2994c17\"},\"headline\":\"Como fazer um logotipo responsivo\",\"datePublished\":\"2021-05-07T04:52:29+00:00\",\"dateModified\":\"2021-05-07T05:22:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#primaryimage\"},\"articleSection\":\"Marketing\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/logotipo-responsivo\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/379800fa881357672b0119e4a2994c17\",\"name\":\"Ilya Lavrov\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/713d4593fdd72be34274409471435888?s=96&d=mm&r=g\",\"caption\":\"Ilya Lavrov\"},\"description\":\"Sou designer de produto e gr\\u00e1fico com 10 anos de experi\\u00eancia. Escrever sobre branding, cria\\u00e7\\u00e3o de logotipos e neg\\u00f3cios.\",\"sameAs\":[\"http:\/\/ilyalavrov.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1748"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=1748"}],"version-history":[{"count":14,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1748\/revisions"}],"predecessor-version":[{"id":8918,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1748\/revisions\/8918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/6892"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=1748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=1748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=1748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}