{"id":1565,"date":"2021-05-07T04:36:14","date_gmt":"2021-05-07T04:36:14","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=1565"},"modified":"2022-03-15T07:29:26","modified_gmt":"2022-03-15T07:29:26","slug":"oakland-raiders-logo","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/","title":{"rendered":"Significado Logotipo dos Oakland Raiders &#8211; Hist\u00f3ria e Evolu\u00e7\u00e3o"},"content":{"rendered":"\n<p>Hoje vamos contar uma hist\u00f3ria instrutiva sobre como chegar ao topo da <a href=\"https:\/\/turbologo.com\/pt\/blog\/nfl-logo\/\">NFL<\/a> sendo um completo forasteiro. Essas equipes n\u00e3o podem se gabar de ter f\u00e3s suficientes para encher um est\u00e1dio. E nenhum time se orgulharia de ter muito poucas vit\u00f3rias no campeonato do Super Bowl. E tr\u00eas delas foram deixadas nos anos 70 de qualquer forma. No entanto, a efic\u00e1cia em campo pode n\u00e3o ser o objetivo principal de uma equipe. Os Oakland Raiders e seu logotipo s\u00e3o um excelente exemplo para aqueles que pretendem <a href=\"https:\/\/turbologo.com\/pt\">desenhar a marca<\/a> sozinhos!<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2>Hist\u00f3ria do logotipo dos Raiders<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/Oakland-Raiders-First-Logo.png\" alt=\"Primeiro logotipo dos Oakland Raiders\" class=\"wp-image-1608\" title=\"Primeiro logotipo dos Oakland Raiders\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133443\/Oakland-Raiders-First-Logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133443\/Oakland-Raiders-First-Logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133443\/Oakland-Raiders-First-Logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133443\/Oakland-Raiders-First-Logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>Inicialmente, o clube estava sediado em Oakland, Calif\u00f3rnia, pertencente \u00e0 divis\u00e3o ocidental. O primeiro nome da equipe era Oakland Seniors, em homenagem aos primeiros colonos espanh\u00f3is. No entanto, houve um erro no nome e se dirigir aos jogadores como &#8220;seniors&#8221; \u00e9 simplesmente rid\u00edculo, pretensioso e irritante ao mesmo tempo. Como resultado, todos estavam zombando da equipe. O in\u00edcio acabou dando errado.<\/p>\n\n\n\n<p>O nome foi mudado para evitar ser ridicularizado na m\u00eddia. &#8220;Oakland Raiders&#8221; soou muito mais plaus\u00edvel e o p\u00fablico tamb\u00e9m gostou. Entretanto, ainda n\u00e3o est\u00e1 claro o que significam o nome e o logotipo. Na verdade, \u00e9 dif\u00edcil distinguir um pirata de um invasor. Ambos est\u00e3o invadindo. Podem ser piratas que o fazem no mar, mas n\u00e3o o fazem o tempo todo. Al\u00e9m disso, come\u00e7ando com o primeiro logotipo dos Raiders, a sugest\u00e3o foi enfatizada. O significado disso era claro ou at\u00e9 mesmo eloquente. O retrato de Randolph Scott foi usado para fazer o logotipo. Ele tamb\u00e9m estava usando uma pala para os olhos e um capacete de futebol. E dois sabres cruzados para um fundo estavam com certeza parecendo agressivos. Um rosto de car\u00e1ter ocidental, sua mand\u00edbula larga e um olhar agu\u00e7ado em seu rosto estavam enfatizando uma firme determina\u00e7\u00e3o da equipe.<\/p>\n\n\n\n<h2>Evolu\u00e7\u00e3o do logotipo dos Oakland Raiders<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/Oakland-Raiders-logo-history-1.png\" alt=\"Hist\u00f3ria do logotipo dos Oakland Raiders\" class=\"wp-image-1612\" title=\"Hist\u00f3ria do logotipo dos Oakland Raiders\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133440\/Oakland-Raiders-logo-history-1.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133440\/Oakland-Raiders-logo-history-1-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133440\/Oakland-Raiders-logo-history-1-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133440\/Oakland-Raiders-logo-history-1.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>Do ponto de vista comercial, a solu\u00e7\u00e3o era realmente pontuar. Apesar de a equipe ser decente, as vendas estavam aumentando um dia ap\u00f3s o outro. Devido ao seu comportamento flamboyant e branding cuidadoso, os Raiders superaram qualquer outra equipe quando se trata de com\u00e9rcio. Eles vendem realmente muito, e nenhum outro time consegue superar sua pontua\u00e7\u00e3o. E os f\u00e3s do time t\u00eam at\u00e9 mesmo seu pr\u00f3prio nome para o time. Eles a chamam de &#8220;Raiders Nation&#8221;. Basta descobrir o significado.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/Oakland-Raiders-Primary-Logo.png\" alt=\"Logotipo prim\u00e1rio dos Oakland Raiders\" class=\"wp-image-1610\" title=\"Logotipo prim\u00e1rio dos Oakland Raiders\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133442\/Oakland-Raiders-Primary-Logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133442\/Oakland-Raiders-Primary-Logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133442\/Oakland-Raiders-Primary-Logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133442\/Oakland-Raiders-Primary-Logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>Muito logicamente, o logotipo dos Raiders permanece o mesmo que foi projetado h\u00e1 muito tempo. Mesmo a fonte n\u00e3o foi alterada em nada. Ainda \u00e9 grave e empurrante. Mesmo seu nome &#8220;Twentieth Century MT Ultrabold&#8221; parece suportar uma imagem de agress\u00e3o.<\/p>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1647329310167\"><strong class=\"schema-faq-question\">O que s\u00e3o os Oakland Raiders?<\/strong> <p class=\"schema-faq-answer\">Formado em 1960, os Raiders s\u00e3o um time americano de futebol profissional de Oakland, Calif\u00f3rnia. Durante suas primeiras dez longas temporadas, os Raiders fizeram parte da Liga Americana de Futebol; desde a fus\u00e3o de 1970 tanto da AFL quanto da NFL, eles est\u00e3o na Liga Nacional de Futebol. Os Oakland Raiders fazem parte da Divis\u00e3o Ocidental da Associa\u00e7\u00e3o Americana de Futebol desde 2013. Durante cinq\u00fcenta e quatro longos per\u00edodos, os Raiders t\u00eam tido um sucesso consider\u00e1vel.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329324656\"><strong class=\"schema-faq-question\">De quem \u00e9 o rosto no logotipo dos Oakland raiders?<\/strong> <p class=\"schema-faq-answer\">Ainda n\u00e3o est\u00e1 claro o que o nome e o logotipo significam. Na verdade, \u00e9 dif\u00edcil dizer a diferen\u00e7a entre um pirata e um invasor. Ambos fazem raids. Talvez os piratas o fa\u00e7am no mar, mas n\u00e3o o tempo todo. Um retrato de Randolph Scott foi usado para criar o logotipo. Ele estava usando uma pala para os olhos e um capacete de futebol tamb\u00e9m. E os sabres g\u00eameos cruzados no pano de fundo certamente pareciam brutais. A express\u00e3o facial do personagem ocidental, seu queixo largo e o olhar agu\u00e7ado ressaltaram a firme determina\u00e7\u00e3o do time.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329335596\"><strong class=\"schema-faq-question\">Quem inventou o logotipo dos Oakland Raiders?<\/strong> <p class=\"schema-faq-answer\">O Oakland Raiders de 1963 recrutou Al Davis \u00e9 o novo treinador chefe, que estava no clube h\u00e1 30 anos, com um recorde fenomenal. Este homem talentoso \u00e9 quem projetou o logotipo da equipe. Seguindo a uni\u00e3o da AFL e da NFL, o clube de futebol Oakland, o jovem e promissor Raiders, tornou-se um dos times mais fortes da liga, sob a orienta\u00e7\u00e3o cuidadosa de Davis. O nome de Al Davis, juntamente com os demais jogadores que j\u00e1 jogaram pelos Raiders, est\u00e3o listados no Hall da Fama.<\/p> <\/div> <\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-344\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/tipos-de-logotipos\/\">Tipos de logotipos: uma lista dos principais modelos encontrados na ind\u00fastria<\/a><\/li>\n<li id=\"su-post-1022\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/2019-logo-design-tendencias\/\">Principais tend\u00eancias de design de logotipo de 2019<\/a><\/li>\n<li id=\"su-post-9975\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/extensoes-uteis-do-google-chrome-para-empresas\/\">Extens\u00f5es \u00fateis do Google Chrome para empresas<\/a><\/li>\n<li id=\"su-post-1742\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-da-rebrand\/\">Como reformular o design do seu logotipo<\/a><\/li>\n<li id=\"su-post-9539\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/arquivo-svg\/\">O que \u00e9 um arquivo SVG? Guia de como utiliz\u00e1-lo<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hoje vamos contar uma hist\u00f3ria instrutiva sobre como chegar ao topo da NFL sendo um completo forasteiro. Essas equipes n\u00e3o&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Significado Logotipo dos Oakland Raiders - Hist\u00f3ria e Evolu\u00e7\u00e3o | Turbologo<\/title>\n<meta name=\"description\" content=\"O hist\u00f3rico do logotipo dos Raiders estaria incompleto sem Randolph Scott. O nome da fonte do logotipo dos Raiders parece apoiar a id\u00e9ia de que a equipe seja inabal\u00e1vel e selvagem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Significado Logotipo dos Oakland Raiders - Hist\u00f3ria e Evolu\u00e7\u00e3o | Turbologo\" \/>\n<meta property=\"og:description\" content=\"O hist\u00f3rico do logotipo dos Raiders estaria incompleto sem Randolph Scott. O nome da fonte do logotipo dos Raiders parece apoiar a id\u00e9ia de que a equipe seja inabal\u00e1vel e selvagem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T04:36:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T07:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133441\/oakland-raiders-logo-cover.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Victoria Maybach\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133441\/oakland-raiders-logo-cover.png\",\"width\":1000,\"height\":700,\"caption\":\"Oakland Raiders logo cover\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/\",\"name\":\"Significado Logotipo dos Oakland Raiders - Hist\\u00f3ria e Evolu\\u00e7\\u00e3o | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#primaryimage\"},\"datePublished\":\"2021-05-07T04:36:14+00:00\",\"dateModified\":\"2022-03-15T07:29:26+00:00\",\"description\":\"O hist\\u00f3rico do logotipo dos Raiders estaria incompleto sem Randolph Scott. O nome da fonte do logotipo dos Raiders parece apoiar a id\\u00e9ia de que a equipe seja inabal\\u00e1vel e selvagem.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/\",\"name\":\"Significado Logotipo dos Oakland Raiders &#8211; Hist\\u00f3ria e Evolu\\u00e7\\u00e3o\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\"},\"headline\":\"Significado Logotipo dos Oakland Raiders &#8211; Hist\\u00f3ria e Evolu\\u00e7\\u00e3o\",\"datePublished\":\"2021-05-07T04:36:14+00:00\",\"dateModified\":\"2022-03-15T07:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#primaryimage\"},\"articleSection\":\"Branding\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\",\"name\":\"Victoria Maybach\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/227e182dfb1b824e5a150c453121a92b?s=96&d=mm&r=g\",\"caption\":\"Victoria Maybach\"},\"description\":\"Editor de blogs e especialista em marketing de conte\\u00fado da Turbologo. Escrevendo sobre marketing e design. Os artigos de Victoria cont\\u00eam dicas \\u00fateis sobre como construir uma marca e promov\\u00ea-la online.\"},{\"@type\":\"ItemList\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#article\"},\"numberOfItems\":3,\"itemListElement\":[{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329310167\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329324656\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329335596\"}]},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329310167\",\"position\":1,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329310167\",\"name\":\"O que s\\u00e3o os Oakland Raiders?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Formado em 1960, os Raiders s\\u00e3o um time americano de futebol profissional de Oakland, Calif\\u00f3rnia. Durante suas primeiras dez longas temporadas, os Raiders fizeram parte da Liga Americana de Futebol; desde a fus\\u00e3o de 1970 tanto da AFL quanto da NFL, eles est\\u00e3o na Liga Nacional de Futebol. Os Oakland Raiders fazem parte da Divis\\u00e3o Ocidental da Associa\\u00e7\\u00e3o Americana de Futebol desde 2013. Durante cinq\\u00fcenta e quatro longos per\\u00edodos, os Raiders t\\u00eam tido um sucesso consider\\u00e1vel.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329324656\",\"position\":2,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329324656\",\"name\":\"De quem \\u00e9 o rosto no logotipo dos Oakland raiders?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Ainda n\\u00e3o est\\u00e1 claro o que o nome e o logotipo significam. Na verdade, \\u00e9 dif\\u00edcil dizer a diferen\\u00e7a entre um pirata e um invasor. Ambos fazem raids. Talvez os piratas o fa\\u00e7am no mar, mas n\\u00e3o o tempo todo. Um retrato de Randolph Scott foi usado para criar o logotipo. Ele estava usando uma pala para os olhos e um capacete de futebol tamb\\u00e9m. E os sabres g\\u00eameos cruzados no pano de fundo certamente pareciam brutais. A express\\u00e3o facial do personagem ocidental, seu queixo largo e o olhar agu\\u00e7ado ressaltaram a firme determina\\u00e7\\u00e3o do time.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329335596\",\"position\":3,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/oakland-raiders-logo\/#faq-question-1647329335596\",\"name\":\"Quem inventou o logotipo dos Oakland Raiders?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"O Oakland Raiders de 1963 recrutou Al Davis \\u00e9 o novo treinador chefe, que estava no clube h\\u00e1 30 anos, com um recorde fenomenal. Este homem talentoso \\u00e9 quem projetou o logotipo da equipe. Seguindo a uni\\u00e3o da AFL e da NFL, o clube de futebol Oakland, o jovem e promissor Raiders, tornou-se um dos times mais fortes da liga, sob a orienta\\u00e7\\u00e3o cuidadosa de Davis. O nome de Al Davis, juntamente com os demais jogadores que j\\u00e1 jogaram pelos Raiders, est\\u00e3o listados no Hall da Fama.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1565"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=1565"}],"version-history":[{"count":7,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1565\/revisions"}],"predecessor-version":[{"id":9811,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1565\/revisions\/9811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/1611"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=1565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=1565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=1565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}