{"id":1432,"date":"2019-11-13T21:46:57","date_gmt":"2019-11-13T21:46:57","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=1432"},"modified":"2021-05-09T10:59:40","modified_gmt":"2021-05-09T10:59:40","slug":"chicago-cubs-logo","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/","title":{"rendered":"Logotipo dos Chicago Cubs &#8211; Evolu\u00e7\u00e3o e Hist\u00f3ria"},"content":{"rendered":"\n<p class=\"p1\">As pessoas s\u00e9rias se interessaram pelo beisebol no final do s\u00e9culo XIX. Era uma era dourada do beisebol na Am\u00e9rica quando o transformou em um esporte nacional. Todos os tipos de empres\u00e1rios cheiravam dinheiro l\u00e1. Independentemente de muitas previs\u00f5es, o beisebol n\u00e3o acabou rapidamente. O beisebol continua sendo um jogo importante e favorito para muitos de n\u00f3s. E \u00e9 bastante l\u00f3gico que as equipes mais fortes foram fundadas h\u00e1 muito tempo. E a hist\u00f3ria de uma dessas equipes \u00e9 para ser contada aqui.<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2 class=\"p3\">Hist\u00f3ria de cria\u00e7\u00e3o de imagens do logotipo dos Le\u00f5ezinhos<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/chicago-cubs-first-logo.png\" alt=\"Primeiro logotipo das crias de Chicago\" class=\"wp-image-1500\" title=\"Primeiro logotipo das crias de Chicago\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133523\/chicago-cubs-first-logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133523\/chicago-cubs-first-logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133523\/chicago-cubs-first-logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133523\/chicago-cubs-first-logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p class=\"p1\">Os Chicago Cubs foram uma das equipes mais fortes de uma liga a partir do s\u00e9culo XIX. E o nome inicial e o mais antigo da equipe era Chicago Orphans, mas foi removido apressadamente. Tudo come\u00e7ou com muitas vit\u00f3rias conquistadas pela equipe no in\u00edcio do s\u00e9culo passado. Eles esperavam muito dos Le\u00f5ezinhos, mas as coisas ficaram feias depois que eles venceram a World Series em 1908.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/chicago-cubs-logo-history.png\" alt=\"Hist\u00f3ria do logotipo dos filhotes de Chicago\" class=\"wp-image-1502\" title=\"Hist\u00f3ria do logotipo dos filhotes de Chicago\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo-history.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo-history-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo-history-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo-history.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p class=\"p1\">Inicialmente, uma antiga <a href=\"https:\/\/turbologo.com\/pt\/blog\/image-file-formats\/\">imagem<\/a> do logotipo dos Chicago Cubs parecia a letra &#8220;C&#8221; escrita em tipo g\u00f3tico. E &#8220;C&#8221; significava Chicago, \u00e9 claro. O tra\u00e7ado da letra foi alterado v\u00e1rias vezes. Algumas op\u00e7\u00f5es inclu\u00edam entalhes, outras n\u00e3o. A cor variava entre o azul e o cinza escuro. E finalmente, o logotipo dos Cubs desenvolveu um novo estilo em 1908. Um filhote de urso fulvo foi moldado em &#8220;C&#8221; segurando um taco de beisebol em suas patas. Talvez tenha sido esta altera\u00e7\u00e3o do logotipo que afetou misticamente o destino de todos os Le\u00f5ezinhos.<\/p>\n\n\n\n<h2 class=\"p3\">Uma maldi\u00e7\u00e3o de equipe<\/h2>\n\n\n\n<p class=\"p1\">Uma sucess\u00e3o de fracassos \u00e9 uma vis\u00e3o comum nos esportes. Quando \u00e9 dif\u00edcil afirmar raz\u00f5es diretas, as pessoas muitas vezes tendem a inventar explica\u00e7\u00f5es estranhas. Afinal, nenhuma outra equipe sofreu uma sucess\u00e3o t\u00e3o longa de fracassos. Isso aconteceu nos anos 40 quando os Chicago Cubs rejeitaram outra varia\u00e7\u00e3o do <a href=\"https:\/\/turbologo.com\/pt\/\">logotipo<\/a>. Em vez disso, foi completamente alterada e um focinho de urso irado e furioso aconteceu com um ador\u00e1vel filhote de urso rodeado por &#8220;C&#8221;. Foi bastante inesperado e incomum para a equipe e os torcedores tamb\u00e9m n\u00e3o entenderam bem a ess\u00eancia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/chicago-cubs-photo.png\" alt=\"Foto dos filhotes de Chicago\" class=\"wp-image-1504\" title=\"Foto dos filhotes de Chicago\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133520\/chicago-cubs-photo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133520\/chicago-cubs-photo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133520\/chicago-cubs-photo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133520\/chicago-cubs-photo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p class=\"p1\">E era apenas o momento perfeito para que outra hist\u00f3ria acontecesse. A equipe tinha um certo f\u00e3 que amava absolutamente as cabras. Ele acreditava firmemente que as cabras trazem sorte. E seu nome era William Sianis. Era uma vez, ele e seu bode, ambos com ingressos, foram assistir ao jogo. Como o bode n\u00e3o tinha o ar mais agrad\u00e1vel ao seu redor, ambos foram convidados a deixar a partida. Sianis tinha ficado louco por causa disso e amaldi\u00e7oou a equipe. Ele disse que n\u00e3o haveria mais vit\u00f3ria para a equipe. E a maldi\u00e7\u00e3o se tornou realidade!<\/p>\n\n\n\n<h2 class=\"p3\">Altera\u00e7\u00e3o do logotipo dos Chicago Cubs<\/h2>\n\n\n\n<p class=\"p1\">Logo ap\u00f3s o evento, outra mudan\u00e7a de marca foi emitida em 1946. A carta &#8220;C&#8221; retornou, mas n\u00e3o havia nenhuma cria dentro dela. Havia a abrevia\u00e7\u00e3o UBS. Assim, a letra &#8220;C&#8221; come\u00e7ou a simbolizar n\u00e3o apenas Chicago, mas tamb\u00e9m um nome de equipe. As <a href=\"https:\/\/turbologo.com\/pt\/blog\/combinacoes-de-cores\/\">cores<\/a> vermelha, branca e azul foram retiradas da bandeira desta vez. Os filhotes estavam experimentando detalhes do logotipo e delineando muitas vezes, mas n\u00e3o mudaram seu logotipo completamente.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/12\/chicago-cubs-logo.png\" alt=\"Logotipo dos filhotes de Chicago\" class=\"wp-image-1503\" title=\"Logotipo dos filhotes de Chicago\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133521\/chicago-cubs-logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p class=\"p1\">No entanto, todas as aberturas com cores diferentes, todas as tentativas de rebranding foram em v\u00e3o at\u00e9 2016. O logotipo de 1979 n\u00e3o foi alterado significativamente. Ele ainda foi esbo\u00e7ado com uma linha azul espessa. No entanto, de alguma forma, a equipe conseguiu superar seu destino retorcido. A maldi\u00e7\u00e3o do Billy Goat foi levantada no outono de 2016! Os Chicago Cubs ganharam a S\u00e9rie Mundial pela primeira vez em 100 anos! O f\u00e3 mais famoso de uma equipe, Bill Murray, estava sobre a lua. Como todos os outros f\u00e3s, que estavam chorando nas arquibancadas. \u00c0s vezes n\u00e3o se trata de logotipo ou marca, trata-se simplesmente de sorte!<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-1569\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/chicago-bulls-logo\/\">Design do Logotipo Chicago Bulls &#8211; Hist\u00f3ria e Evolu\u00e7\u00e3o<\/a><\/li>\n<li id=\"su-post-1422\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logos-for-gamers\/\">Logotipos para gamers \u2013 ideias de design e modelos para gamers<\/a><\/li>\n<li id=\"su-post-1424\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/nfl-logo\/\">A hist\u00f3ria do design do logotipo da NFL<\/a><\/li>\n<li id=\"su-post-1567\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/skype-logo\/\">Design e Hist\u00f3ria do Logotipo Skype &#8211; qual a cor e fonte<\/a><\/li>\n<li id=\"su-post-9870\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipos-criativos-50-exemplos-notaveis\/\">Logotipos criativos: 50 exemplos not\u00e1veis<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>As pessoas s\u00e9rias se interessaram pelo beisebol no final do s\u00e9culo XIX. Era uma era dourada do beisebol na Am\u00e9rica&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Logotipo dos Chicago Cubs - Evolu\u00e7\u00e3o e Hist\u00f3ria | Turbologo<\/title>\n<meta name=\"description\" content=\"O logotipo dos Chicago Cubs est\u00e1 em desacordo quando se trata de escolher entre uma imagem de urso e o desenho de letras e estrelas. As imagens do logotipo dos Chicago Cubs muitas vezes incluem letras iniciais do nome da equipe ou de uma cidade de origem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logotipo dos Chicago Cubs - Evolu\u00e7\u00e3o e Hist\u00f3ria | Turbologo\" \/>\n<meta property=\"og:description\" content=\"O logotipo dos Chicago Cubs est\u00e1 em desacordo quando se trata de escolher entre uma imagem de urso e o desenho de letras e estrelas. As imagens do logotipo dos Chicago Cubs muitas vezes incluem letras iniciais do nome da equipe ou de uma cidade de origem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-13T21:46:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-09T10:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133522\/chicago-cubs-logo-cover.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Victoria Maybach\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/12\/19133522\/chicago-cubs-logo-cover.png\",\"width\":1000,\"height\":700,\"caption\":\"Chicago cubs logo cover\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/\",\"name\":\"Logotipo dos Chicago Cubs - Evolu\\u00e7\\u00e3o e Hist\\u00f3ria | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#primaryimage\"},\"datePublished\":\"2019-11-13T21:46:57+00:00\",\"dateModified\":\"2021-05-09T10:59:40+00:00\",\"description\":\"O logotipo dos Chicago Cubs est\\u00e1 em desacordo quando se trata de escolher entre uma imagem de urso e o desenho de letras e estrelas. As imagens do logotipo dos Chicago Cubs muitas vezes incluem letras iniciais do nome da equipe ou de uma cidade de origem.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/\",\"name\":\"Logotipo dos Chicago Cubs &#8211; Evolu\\u00e7\\u00e3o e Hist\\u00f3ria\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\"},\"headline\":\"Logotipo dos Chicago Cubs &#8211; Evolu\\u00e7\\u00e3o e Hist\\u00f3ria\",\"datePublished\":\"2019-11-13T21:46:57+00:00\",\"dateModified\":\"2021-05-09T10:59:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#primaryimage\"},\"articleSection\":\"Branding\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/chicago-cubs-logo\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\",\"name\":\"Victoria Maybach\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/227e182dfb1b824e5a150c453121a92b?s=96&d=mm&r=g\",\"caption\":\"Victoria Maybach\"},\"description\":\"Editor de blogs e especialista em marketing de conte\\u00fado da Turbologo. Escrevendo sobre marketing e design. Os artigos de Victoria cont\\u00eam dicas \\u00fateis sobre como construir uma marca e promov\\u00ea-la online.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1432"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=1432"}],"version-history":[{"count":8,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1432\/revisions"}],"predecessor-version":[{"id":9034,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1432\/revisions\/9034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/1501"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=1432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=1432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=1432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}