{"id":1202,"date":"2021-05-07T04:25:42","date_gmt":"2021-05-07T04:25:42","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=1202"},"modified":"2021-05-08T13:47:42","modified_gmt":"2021-05-08T13:47:42","slug":"star-wars-logo","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/","title":{"rendered":"Star Wars Logos &#8211; evolu\u00e7\u00e3o e hist\u00f3ria"},"content":{"rendered":"\n<p>Era 25 de maio quando surgiu a saga &#8220;Guerra das Estrelas&#8221;. O fato de um \u00fanico filme ter mudado toda a ind\u00fastria e afetado o pr\u00f3prio mundo \u00e9 realmente magn\u00edfico. George Lucas foi o primeiro a usar <a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-do-computador\/\">computa\u00e7\u00e3o<\/a> gr\u00e1fica original, tecnologia Dolby Surround e resolu\u00e7\u00e3o de v\u00eddeo digital. Mas qual \u00e9 o segredo de um sucesso t\u00e3o inacredit\u00e1vel? Existe algo que possamos aprender com eles? Vamos descobrir.<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2>Logotipo original da Guerra das Estrelas<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-70s-logo.png\" alt=\"Logotipo da Guerra das Estrelas dos anos 70\" class=\"wp-image-1276\" title=\"Logotipo da Guerra das Estrelas dos anos 70\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133643\/star-wars-70s-logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133643\/star-wars-70s-logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133643\/star-wars-70s-logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133643\/star-wars-70s-logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>A fic\u00e7\u00e3o cient\u00edfica do s\u00e9culo 20 tem seu pr\u00f3prio e \u00fanico encanto. Todos aqueles sonhos sobre o espa\u00e7o longe, planetas inexplorados, aventuras e, junto com ele, uma certa ingenuidade. Tudo isso \u00e9 expresso pelo primeiro logotipo da Guerra das Estrelas. Ele foi desenhado de uma maneira inimit\u00e1vel para aqueles que procuram abandonar a realidade mon\u00f3tona da vida cotidiana.<\/p>\n\n\n\n<p>Vamos analis\u00e1-lo passo a passo. O tri\u00e2ngulo \u00e9 uma boa solu\u00e7\u00e3o para um <a href=\"https:\/\/turbologo.com\/pt\/\">logotipo<\/a>, pois simboliza estabilidade e confiabilidade. Independentemente da ocupa\u00e7\u00e3o da empresa, \u00e9 uma das melhores formas poss\u00edveis. Al\u00e9m disso, o tri\u00e2ngulo \u00e9 saliente e pontiagudo, pois o torna mais atraente aos olhos. Al\u00e9m disso, voc\u00ea pode facilmente colocar um c\u00edrculo ou esfera no tri\u00e2ngulo, e em nosso caso ele \u00e9 representado por um planeta carmesim, abrigando aventuras de tirar o f\u00f4lego. E uma figura de her\u00f3i da Guerra das Estrelas divide o logotipo em duas partes iguais, atraindo assim uma aten\u00e7\u00e3o. No topo, h\u00e1 uma estrela de tamanho m\u00e9dio, mas bastante brilhante, que tamb\u00e9m \u00e9 um s\u00edmbolo rom\u00e2ntico e convidativo, que tem sido usado no pr\u00f3prio filme. Um lettering brilhante est\u00e1 se somando \u00e0 base do logotipo. Portanto, como voc\u00ea pode ver, este logotipo \u00e9 colorido, mas de composi\u00e7\u00e3o geom\u00e9trica simples, pois a simplicidade sempre bate a fantasia.<\/p>\n\n\n\n<p>Foi um dos melhores logotipos daqueles anos. Estranhamente, no entanto, mas foi o que mais se conseguiu com a Guerra das Estrelas. O marketing adequado tornou a franquia t\u00e3o conhecida quanto ela \u00e9. Portanto, se voc\u00ea \u00e9 um rom\u00e2ntico, sonhando com estrelas e viagens, este logotipo certamente o picar\u00e1.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-1977-logo.png\" alt=\"Logotipo da Guerra das Estrelas de 1977\" class=\"wp-image-1277\" title=\"Logotipo da Guerra das Estrelas de 1977\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-1977-logo.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-1977-logo-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-1977-logo-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-1977-logo.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<h2>Que tipo de letra \u00e9 o logotipo da Guerra das Estrelas<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-logo-the-empire-strikes-back.png\" alt=\"Logotipo da Guerra das Estrelas - o imp\u00e9rio ataca de volta\" class=\"wp-image-1278\" title=\"Logotipo da Guerra das Estrelas - o imp\u00e9rio ataca de volta\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-logo-the-empire-strikes-back.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-logo-the-empire-strikes-back-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-logo-the-empire-strikes-back-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133642\/star-wars-logo-the-empire-strikes-back.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>A fonte Futura Display foi inicialmente escolhida para o logotipo da Star Wars, mas depois foi alterada para Precis. Depois disso, George Lucas considerou que todas as op\u00e7\u00f5es dadas eram inadequadas para seu design. Uma parte significativa da hist\u00f3ria \u00e9 contada sobre o Imp\u00e9rio, um inimigo de tudo o que \u00e9 bom. O Imp\u00e9rio \u00e9 governado pelo punho de ferro e semeia sua ideologia, muito parecida com a Alemanha nazista. Talvez seja apenas a raz\u00e3o para George Lucas decidir tornar o logotipo um pouco nazista. E ele ordenou exatamente isso a seus designers.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-logo-3.png\" alt=\"Logotipo 3 da Guerra das Estrelas\" class=\"wp-image-1279\" title=\"Logotipo 3 da Guerra das Estrelas\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133641\/star-wars-logo-3.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133641\/star-wars-logo-3-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133641\/star-wars-logo-3-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133641\/star-wars-logo-3.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>A fonte Helevtica Black foi escolhida para uma nova varia\u00e7\u00e3o do logotipo. Os designers passaram muito tempo fazendo com que ele se adaptasse \u00e0s necessidades de Lucas. &#8220;W&#8221; em &#8220;Wars&#8221; \u00e9 deliberadamente afiada, pontiaguda e intimidadora. A carta foi desenhada um pouco mais tarde, e o logotipo original de &#8220;Guerra nas Estrelas&#8221; sofreu pequenas mudan\u00e7as.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-logo-the-empire-strikes-back-posters.png\" alt=\"Logotipo da Guerra das Estrelas - o imp\u00e9rio ataca com cartazes\" class=\"wp-image-1282\" title=\"Logotipo da Guerra das Estrelas - o imp\u00e9rio ataca com cartazes\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133639\/star-wars-logo-the-empire-strikes-back-posters.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133639\/star-wars-logo-the-empire-strikes-back-posters-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133639\/star-wars-logo-the-empire-strikes-back-posters-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133639\/star-wars-logo-the-empire-strikes-back-posters.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<h2>E como est\u00e1 indo a franquia hoje em dia?<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-logos.png\" alt=\"Logotipos da Guerra das Estrelas\" class=\"wp-image-1281\" title=\"Logotipos da Guerra das Estrelas\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logos.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logos-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logos-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logos.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>Pode-se debater o valor art\u00edstico do Star Wars, mas seu valor financeiro est\u00e1 fora de quest\u00e3o. Dificilmente se encontra uma crian\u00e7a, que n\u00e3o estava sempre pedindo a seus pais uma lapiseira, uma bolsa escolar ou um brinquedo com o logotipo da Guerra nas Estrelas. \u00c9 claro que h\u00e1 muitos adultos que compram mercadorias com aquele comerciante ou v\u00e3o ao cinema. Uma transa\u00e7\u00e3o aproximada \u00e9 de cerca de 10 bilh\u00f5es por ano.<\/p>\n\n\n\n<p>E tudo isso \u00e9 apenas uma hist\u00f3ria simples e despretensiosa. A prop\u00f3sito, aceite pelo logotipo muitas outras solu\u00e7\u00f5es visuais em Star Wars. Os usu\u00e1rios podem se perguntar como desenhar o logotipo da Guerra nas Estrelas, j\u00e1 que o efeito de legendas rastejantes atingiu os cora\u00e7\u00f5es de muitos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1110\" height=\"1015\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/11\/star-wars-logo-history.jpg\" alt=\"Evolu\u00e7\u00e3o do logotipo Star Wars\" class=\"wp-image-1280\" title=\"Evolu\u00e7\u00e3o do logotipo Star Wars\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logo-history.jpg 1110w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logo-history-300x274.jpg 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logo-history-768x702.jpg 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133640\/star-wars-logo-history.jpg\" data-full-size=\"1110x1015\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/turbologo.com\/pt\/blog\/combinacoes-de-cores\/\">As cores do logotipo<\/a> da Star War s\u00e3o amarelo profundo sobre um fundo preto. \u00c9 justamente esse o caso quando as pessoas se lembram bem dele e n\u00e3o o confundem com outra coisa, pois h\u00e1 uma brilhante hist\u00f3ria de sucesso por tr\u00e1s do logotipo da Guerra das Estrelas.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-9877\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/como-criar-um-certificado-de-presente\/\">Como criar um certificado de presente<\/a><\/li>\n<li id=\"su-post-684\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/historia-do-logotipo\/\">De onde v\u00eam os logotipos? Breve hist\u00f3ria do design de logotipo<\/a><\/li>\n<li id=\"su-post-8279\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/como-exibir-o-logotipo-do-google-places\/\">Como exibir o logotipo e as avalia\u00e7\u00f5es do Google Places em seu site WordPress<\/a><\/li>\n<li id=\"su-post-1039\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/design-do-logotipo-da-empresa\/\">Design do logotipo da empresa &#8211; ideias e dicas<\/a><\/li>\n<li id=\"su-post-795\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/apple-logo\/\">A hist\u00f3ria do logotipo da Apple<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Era 25 de maio quando surgiu a saga &#8220;Guerra das Estrelas&#8221;. O fato de um \u00fanico filme ter mudado toda&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Star Wars Logos - evolu\u00e7\u00e3o e hist\u00f3ria | Turbologo<\/title>\n<meta name=\"description\" content=\"O logotipo original da Guerra das Estrelas \u00e9 um s\u00edmbolo de planetas inexplorados e de aventura. Para desenhar o logotipo da Guerra das Estrelas voc\u00ea vai precisar de algumas cores amarelas profundas e pretas absolutas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Star Wars Logos - evolu\u00e7\u00e3o e hist\u00f3ria | Turbologo\" \/>\n<meta property=\"og:description\" content=\"O logotipo original da Guerra das Estrelas \u00e9 um s\u00edmbolo de planetas inexplorados e de aventura. Para desenhar o logotipo da Guerra das Estrelas voc\u00ea vai precisar de algumas cores amarelas profundas e pretas absolutas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T04:25:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-08T13:47:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133638\/star-wars-illustration.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Victoria Maybach\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/11\/19133638\/star-wars-illustration.jpg\",\"width\":1000,\"height\":700},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/\",\"name\":\"Star Wars Logos - evolu\\u00e7\\u00e3o e hist\\u00f3ria | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#primaryimage\"},\"datePublished\":\"2021-05-07T04:25:42+00:00\",\"dateModified\":\"2021-05-08T13:47:42+00:00\",\"description\":\"O logotipo original da Guerra das Estrelas \\u00e9 um s\\u00edmbolo de planetas inexplorados e de aventura. Para desenhar o logotipo da Guerra das Estrelas voc\\u00ea vai precisar de algumas cores amarelas profundas e pretas absolutas.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/\",\"name\":\"Star Wars Logos &#8211; evolu\\u00e7\\u00e3o e hist\\u00f3ria\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\"},\"headline\":\"Star Wars Logos &#8211; evolu\\u00e7\\u00e3o e hist\\u00f3ria\",\"datePublished\":\"2021-05-07T04:25:42+00:00\",\"dateModified\":\"2021-05-08T13:47:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#primaryimage\"},\"articleSection\":\"Branding\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/star-wars-logo\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\",\"name\":\"Victoria Maybach\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/227e182dfb1b824e5a150c453121a92b?s=96&d=mm&r=g\",\"caption\":\"Victoria Maybach\"},\"description\":\"Editor de blogs e especialista em marketing de conte\\u00fado da Turbologo. Escrevendo sobre marketing e design. Os artigos de Victoria cont\\u00eam dicas \\u00fateis sobre como construir uma marca e promov\\u00ea-la online.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1202"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=1202"}],"version-history":[{"count":6,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1202\/revisions"}],"predecessor-version":[{"id":8979,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1202\/revisions\/8979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/1283"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=1202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=1202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=1202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}