{"id":1071,"date":"2021-05-07T04:38:24","date_gmt":"2021-05-07T04:38:24","guid":{"rendered":"https:\/\/turbologo.com\/articles\/?p=1071"},"modified":"2022-03-15T07:36:08","modified_gmt":"2022-03-15T07:36:08","slug":"instagram-logo","status":"publish","type":"post","link":"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/","title":{"rendered":"A evolu\u00e7\u00e3o e a hist\u00f3ria do logotipo da Instagram"},"content":{"rendered":"\n<p>Voc\u00ea consegue se lembrar como se apaixonou pela fotografia? H\u00e1 muito tempo atr\u00e1s, em nossa inf\u00e2ncia, fomos fotografados e nos deram um pequeno cart\u00e3o branco que deveria ter sido sacudido. E ent\u00e3o, de repente, uma foto apareceu no cart\u00e3o em um minuto! Agora voc\u00ea se lembra daqueles momentos maravilhosos e doces. Os que eram fotos completamente amadoras, mas aconchegantes, de polaroides. Por que trocamos? Um servi\u00e7o bem conhecido que a Instagram \u00e9, possuindo os cora\u00e7\u00f5es e mentes de milh\u00f5es. Todas as suas fotos s\u00e3o t\u00e3o agrad\u00e1veis, aconchegantes e acolhedoras como antes. Elas simplesmente se mudaram para a Internet.<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crie seu pr\u00f3prio logotipo com o criador de logotipo Turbologo.<\/b> Leva menos de 5 minutos e nenhuma habilidade de design \u00e9 necess\u00e1ria.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/pt\/criar-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Criar logo online<\/a>\n<\/div><\/div>\n\n\n\n<h2>O que \u00e9 o logotipo da Instagram<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/09\/instagram-first-logo-2010.png\" alt=\"Instagram primeiro logotipo, 2010\" class=\"wp-image-1191\" title=\"Instagram primeiro logotipo, 2010\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133711\/instagram-first-logo-2010.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133711\/instagram-first-logo-2010-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133711\/instagram-first-logo-2010-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133711\/instagram-first-logo-2010.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>N\u00e3o \u00e9 apenas um princ\u00edpio de funcionamento (pequenas fotos amadoras para todos), mas tamb\u00e9m um formato quadrado que nos devolve a essas associa\u00e7\u00f5es. Agora voc\u00ea sabe que este \u00edcone da c\u00e2mera como logotipo n\u00e3o \u00e9 apenas uma coincid\u00eancia. Pode-se dizer que uma c\u00e2mera smartphone parece completamente diferente, mas a quest\u00e3o \u00e9 que a c\u00e2mera retr\u00f4 polaroid invoca lembran\u00e7as doces e os sentimentos das pessoas. Al\u00e9m disso, o servi\u00e7o permitiu n\u00e3o apenas postar as fotos, mas tamb\u00e9m utilizar filtros transparentes, o que, por sua vez, faz com que as fotos pare\u00e7am vintage.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/09\/instagram-second-logo-2010.png\" alt=\"Instagram segundo logotipo, 2010\" class=\"wp-image-1194\" title=\"Instagram segundo logotipo, 2010\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-second-logo-2010.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-second-logo-2010-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-second-logo-2010-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-second-logo-2010.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>O servi\u00e7o apareceu em 2010 e o <a href=\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\">logotipo da Instagram<\/a> de 5 anos de idade n\u00e3o mudou nada. A fonte do logotipo Instagram foi projetada em um <a href=\"https:\/\/turbologo.com\/pt\/blog\/vintage-logo\/\">estilo retro<\/a>, apenas todo o logotipo. Com o passar do tempo, o servi\u00e7o foi se tornando cada vez mais <a href=\"https:\/\/turbologo.com\/pt\/blog\/2019-logo-design-tendencias\/\">famoso<\/a>, desenvolvendo novas fun\u00e7\u00f5es, ent\u00e3o a <a href=\"https:\/\/turbologo.com\/pt\/blog\/design-do-logotipo-da-empresa\/\">empresa<\/a> finalmente decidiu alterar a apar\u00eancia de sua marca. Eles iniciaram um briefing e se perguntaram quais eram os detalhes mais marcantes do antigo logotipo da Instagram. Eram uma lente, um arco-\u00edris e um visor. E assim, todos esses elementos tornaram-se parte de um novo logotipo vetorial da marca.<\/p>\n\n\n\n<h2>Logotipo do Arco-\u00cdris Instagram<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/09\/instagram-old-logo-2011.png\" alt=\"Logotipo antigo da Instagram, 2011\" class=\"wp-image-1193\" title=\"Logotipo antigo da Instagram, 2011\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-old-logo-2011.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-old-logo-2011-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-old-logo-2011-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133709\/instagram-old-logo-2011.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>O arco-\u00edris recebeu a frente, tornando-se uma <a href=\"https:\/\/turbologo.com\/pt\/blog\/combinacoes-de-cores\/\">cor b\u00e1sica do logotipo<\/a> e as lentes e o visor se transformaram em linhas estilizadas. O logotipo continuou sendo harm\u00f4nico e equilibrado, tornando-se assim ainda mais elegante e atualizado do que nunca. Este fato n\u00e3o indica nada al\u00e9m das altas habilidades profissionais dos designers. Um artista, que projetou o logotipo da Instagram, disse que \u00e9 preciso amar seu trabalho para <a href=\"https:\/\/turbologo.com\/pt\/criar-logo\">criar um logotipo de sucesso<\/a>. Ele criou gratuitamente o melhor de seus trabalhos para seus amigos e parentes.<\/p>\n\n\n\n<p>Na verdade, outra raz\u00e3o reside n\u00e3o apenas no profissionalismo e no amor \u00e0 arte, mas tamb\u00e9m em seu campo de interesse. As pessoas, que desenvolvem a Instagram, est\u00e3o no limite das tend\u00eancias <a href=\"https:\/\/turbologo.com\/pt\/blog\/logotipo-da-loja-de-roupas\/\">da moda<\/a>. A intera\u00e7\u00e3o com tudo o que cria a cultura moderna de massa no dia-a-dia e, at\u00e9 certo ponto, elas criam suas pr\u00f3prias tend\u00eancias. \u00c9 justamente esse design que eles oferecem que se torna moderno e na moda, uma vez que os usu\u00e1rios da Instagram passam em m\u00e9dia 21 minutos online e 3,5 bilh\u00f5es de likes s\u00e3o pressionados todos os dias.<\/p>\n\n\n\n<h2>Hist\u00f3rico do logotipo Instagram<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"1024\" height=\"600\" src=\"https:\/\/turbologo.com\/articles\/wp-content\/uploads\/2019\/09\/instagram-new-logo-2016.png\" alt=\"Instagram novo logotipo, 2016\" class=\"wp-image-1192\" title=\"Instagram novo logotipo, 2016\" srcset=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133710\/instagram-new-logo-2016.png 1024w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133710\/instagram-new-logo-2016-300x176.png 300w, https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133710\/instagram-new-logo-2016-768x450.png 768w\" sizes=\"(min-width: 958px) 958px, 100vw\" data-full=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133710\/instagram-new-logo-2016.png\" data-full-size=\"1024x600\" \/><\/figure>\n\n\n\n<p>O hist\u00f3rico do logotipo Instagram n\u00e3o \u00e9 alcan\u00e7ado, pois cada mudan\u00e7a deve ser feita com cautela, dado o n\u00famero de usu\u00e1rios. As vantagens das empresas de tecnologia digital online podem se tornar seus inconvenientes. Seu logotipo favorito de aplica\u00e7\u00e3o chamar\u00e1 sua aten\u00e7\u00e3o imediatamente e voc\u00ea estar\u00e1 querendo saber mais. Al\u00e9m disso, as mudan\u00e7as no sentido de um design mais claro e limpo muitas vezes contribuem muito para o sucesso de tais empresas. Quanto mais um \u00edcone parecer simples e amig\u00e1vel, mais os usu\u00e1rios clicar\u00e3o nele. E cada clique traz lucro hoje em dia. \u00c9 por isso que, ao desenvolver um logotipo para um servi\u00e7o como o Instagram, \u00e9 importante lembrar que a clareza do logotipo significa funcionalidade clara e oportuna.<\/p>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1647329675766\"><strong class=\"schema-faq-question\">Qual \u00e9 a fonte para o logotipo da Instagram?<\/strong> <p class=\"schema-faq-answer\">O logotipo da Instagram foi escrito \u00e0 m\u00e3o especialmente para a marca por um tip\u00f3grafo e designer Mackey Saturday. O roteiro moderno \u00e9 bastante semelhante \u00e0 conhecida fonte Billabong, mas a fonte foi melhorada e come\u00e7ou a possuir um estilo \u00fanico e inimit\u00e1vel. A eleg\u00e2ncia do design foi alcan\u00e7ada devido \u00e0 preval\u00eancia de linhas cursivas que s\u00e3o perfeitas para projetos de branding. A fonte para o logotipo da Instagram \u00e9 principalmente um desenho lac\u00f4nico e elegante em uma simples cor preta e letras curvil\u00edneas redesenhadas com precis\u00e3o.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329692057\"><strong class=\"schema-faq-question\">Que c\u00e2mera \u00e9 o logotipo da Instagram?<\/strong> <p class=\"schema-faq-answer\">Como o pr\u00f3prio fundador da Instagram gostava de fotografia de filme, n\u00e3o \u00e9 de forma alguma surpreendente que o logotipo da marca tenha uma c\u00e2mera. Para ser mais preciso, \u00e9 a c\u00e2mera vintage Bell &amp; Howell, que parece muito simplificada no momento, representando a forma de um quadrado alisado com um c\u00edrculo no centro como uma lente e um pequeno ponto no canto superior direito como um flash. Historicamente, o logotipo passou de ser inspirado em Polaroid para um desenho detalhado do Sierre 120 com uma faixa de arco-\u00edris que simbolizava os filtros de aplica\u00e7\u00e3o.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329699178\"><strong class=\"schema-faq-question\">Quem criou o logotipo da Instagram?<\/strong> <p class=\"schema-faq-answer\">Com o desejo de substituir um design ultrapassado Jan Spalter focou na cria\u00e7\u00e3o de novos contornos do logotipo, consistindo em silhuetas de c\u00e2meras. Foi ele e seus colegas que substitu\u00edram o logotipo, representando a c\u00e2mera instant\u00e2nea anterior por Cole Rise, por uma op\u00e7\u00e3o mais monocrom\u00e1tica.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329707992\"><strong class=\"schema-faq-question\">Por que h\u00e1 uma c\u00e2mera no logotipo da Instagram?<\/strong> <p class=\"schema-faq-answer\">Como o conceito da aplica\u00e7\u00e3o \u00e9 baseado em adicionar fotos ou v\u00eddeos do usu\u00e1rio ao feed na forma de um \u00e1lbum de fotos, n\u00e3o \u00e9 surpreendente que seja o \u00edcone em forma de c\u00e2mera colocado como um major no logotipo da Instagram. Compartilhar e tirar fotografias s\u00e3o as principais caracter\u00edsticas do aplicativo, portanto a c\u00e2mera \u00e9 um atributo insubstitu\u00edvel da fotografia e, sem sua aplica\u00e7\u00e3o, a pr\u00f3pria id\u00e9ia de capturar imagens e obter fotografias seria vi\u00e1vel. Al\u00e9m disso, o fundador da Instagram foi inspirado pela cultura hipster e pelas populares Polaroids da \u00e9poca.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1647329716086\"><strong class=\"schema-faq-question\">Quais s\u00e3o as cores do logotipo da Instagram?<\/strong> <p class=\"schema-faq-answer\">No momento, o \u00edcone fez a re-branding com o advento da nova interface e chegou a um design minimalista com um gradiente brilhante de laranja a rosa. A cor predominante do gradiente \u00e9 o rosa, enquanto esta escolha de cores faz lembrar as cores de um p\u00f4r-do-sol. O logotipo da Instagram evoluiu da vers\u00e3o original em preto e branco para a varia\u00e7\u00e3o colorida e suave do mesmo.<\/p> <\/div> <\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-1787\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/lacoste-logo\/\">Logotipo Lacoste &#8211; Significado, Hist\u00f3ria, Fonte<\/a><\/li>\n<li id=\"su-post-1295\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/xbox-logo\/\">Significado do logotipo e do s\u00edmbolo Xbox &#8211; hist\u00f3ria e evolu\u00e7\u00e3o<\/a><\/li>\n<li id=\"su-post-9649\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/desenho-de-logotipo-vs-marca\/\">Qual \u00e9 a diferen\u00e7a entre Design de Logotipo e Branding?<\/a><\/li>\n<li id=\"su-post-7925\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/cafe-logos\/\">Logotipos Cafe: 20 ideias criativas<\/a><\/li>\n<li id=\"su-post-832\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/pt\/blog\/104-fontes-gratis-para-design-de-logotipo\/\">104 fontes gratuitas perfeitas para design de logotipos<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea consegue se lembrar como se apaixonou pela fotografia? H\u00e1 muito tempo atr\u00e1s, em nossa inf\u00e2ncia, fomos fotografados e nos&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A evolu\u00e7\u00e3o e a hist\u00f3ria do logotipo da Instagram | Turbologo<\/title>\n<meta name=\"description\" content=\"A fonte do logotipo Instagram \u00e9 o resultado de dilig\u00eancia e paci\u00eancia. E a hist\u00f3ria do logotipo Instagram tamb\u00e9m pode ser considerada como uma hist\u00f3ria de sucesso gra\u00e7as a esses atributos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A evolu\u00e7\u00e3o e a hist\u00f3ria do logotipo da Instagram | Turbologo\" \/>\n<meta property=\"og:description\" content=\"A fonte do logotipo Instagram \u00e9 o resultado de dilig\u00eancia e paci\u00eancia. E a hist\u00f3ria do logotipo Instagram tamb\u00e9m pode ser considerada como uma hist\u00f3ria de sucesso gra\u00e7as a esses atributos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sobre branding e logo design - blog oficial da Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T04:38:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T07:36:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133708\/instagram-logo-illustration.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Victoria Maybach\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"4 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2020\/03\/19133249\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Sobre branding e logo design - blog oficial da Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/pt\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/pt\/2019\/09\/19133708\/instagram-logo-illustration.png\",\"width\":1000,\"height\":700,\"caption\":\"Instagram text logo\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#webpage\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\",\"name\":\"A evolu\\u00e7\\u00e3o e a hist\\u00f3ria do logotipo da Instagram | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#primaryimage\"},\"datePublished\":\"2021-05-07T04:38:24+00:00\",\"dateModified\":\"2022-03-15T07:36:08+00:00\",\"description\":\"A fonte do logotipo Instagram \\u00e9 o resultado de dilig\\u00eancia e paci\\u00eancia. E a hist\\u00f3ria do logotipo Instagram tamb\\u00e9m pode ser considerada como uma hist\\u00f3ria de sucesso gra\\u00e7as a esses atributos.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\",\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/\",\"name\":\"A evolu\\u00e7\\u00e3o e a hist\\u00f3ria do logotipo da Instagram\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\"},\"headline\":\"A evolu\\u00e7\\u00e3o e a hist\\u00f3ria do logotipo da Instagram\",\"datePublished\":\"2021-05-07T04:38:24+00:00\",\"dateModified\":\"2022-03-15T07:36:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#primaryimage\"},\"articleSection\":\"Branding\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#\/schema\/person\/58a6a519631095ec516d5f0101c9d0d1\",\"name\":\"Victoria Maybach\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/227e182dfb1b824e5a150c453121a92b?s=96&d=mm&r=g\",\"caption\":\"Victoria Maybach\"},\"description\":\"Editor de blogs e especialista em marketing de conte\\u00fado da Turbologo. Escrevendo sobre marketing e design. Os artigos de Victoria cont\\u00eam dicas \\u00fateis sobre como construir uma marca e promov\\u00ea-la online.\"},{\"@type\":\"ItemList\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#article\"},\"numberOfItems\":5,\"itemListElement\":[{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329675766\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329692057\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329699178\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329707992\"},{\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329716086\"}]},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329675766\",\"position\":1,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329675766\",\"name\":\"Qual \\u00e9 a fonte para o logotipo da Instagram?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"O logotipo da Instagram foi escrito \\u00e0 m\\u00e3o especialmente para a marca por um tip\\u00f3grafo e designer Mackey Saturday. O roteiro moderno \\u00e9 bastante semelhante \\u00e0 conhecida fonte Billabong, mas a fonte foi melhorada e come\\u00e7ou a possuir um estilo \\u00fanico e inimit\\u00e1vel. A eleg\\u00e2ncia do design foi alcan\\u00e7ada devido \\u00e0 preval\\u00eancia de linhas cursivas que s\\u00e3o perfeitas para projetos de branding. A fonte para o logotipo da Instagram \\u00e9 principalmente um desenho lac\\u00f4nico e elegante em uma simples cor preta e letras curvil\\u00edneas redesenhadas com precis\\u00e3o.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329692057\",\"position\":2,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329692057\",\"name\":\"Que c\\u00e2mera \\u00e9 o logotipo da Instagram?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Como o pr\\u00f3prio fundador da Instagram gostava de fotografia de filme, n\\u00e3o \\u00e9 de forma alguma surpreendente que o logotipo da marca tenha uma c\\u00e2mera. Para ser mais preciso, \\u00e9 a c\\u00e2mera vintage Bell &amp; Howell, que parece muito simplificada no momento, representando a forma de um quadrado alisado com um c\\u00edrculo no centro como uma lente e um pequeno ponto no canto superior direito como um flash. Historicamente, o logotipo passou de ser inspirado em Polaroid para um desenho detalhado do Sierre 120 com uma faixa de arco-\\u00edris que simbolizava os filtros de aplica\\u00e7\\u00e3o.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329699178\",\"position\":3,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329699178\",\"name\":\"Quem criou o logotipo da Instagram?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Com o desejo de substituir um design ultrapassado Jan Spalter focou na cria\\u00e7\\u00e3o de novos contornos do logotipo, consistindo em silhuetas de c\\u00e2meras. Foi ele e seus colegas que substitu\\u00edram o logotipo, representando a c\\u00e2mera instant\\u00e2nea anterior por Cole Rise, por uma op\\u00e7\\u00e3o mais monocrom\\u00e1tica.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329707992\",\"position\":4,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329707992\",\"name\":\"Por que h\\u00e1 uma c\\u00e2mera no logotipo da Instagram?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Como o conceito da aplica\\u00e7\\u00e3o \\u00e9 baseado em adicionar fotos ou v\\u00eddeos do usu\\u00e1rio ao feed na forma de um \\u00e1lbum de fotos, n\\u00e3o \\u00e9 surpreendente que seja o \\u00edcone em forma de c\\u00e2mera colocado como um major no logotipo da Instagram. Compartilhar e tirar fotografias s\\u00e3o as principais caracter\\u00edsticas do aplicativo, portanto a c\\u00e2mera \\u00e9 um atributo insubstitu\\u00edvel da fotografia e, sem sua aplica\\u00e7\\u00e3o, a pr\\u00f3pria id\\u00e9ia de capturar imagens e obter fotografias seria vi\\u00e1vel. Al\\u00e9m disso, o fundador da Instagram foi inspirado pela cultura hipster e pelas populares Polaroids da \\u00e9poca.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329716086\",\"position\":5,\"url\":\"https:\/\/turbologo.com\/pt\/blog\/instagram-logo\/#faq-question-1647329716086\",\"name\":\"Quais s\\u00e3o as cores do logotipo da Instagram?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"No momento, o \\u00edcone fez a re-branding com o advento da nova interface e chegou a um design minimalista com um gradiente brilhante de laranja a rosa. A cor predominante do gradiente \\u00e9 o rosa, enquanto esta escolha de cores faz lembrar as cores de um p\\u00f4r-do-sol. O logotipo da Instagram evoluiu da vers\\u00e3o original em preto e branco para a varia\\u00e7\\u00e3o colorida e suave do mesmo.\",\"inLanguage\":\"pt-BR\"},\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1071"}],"collection":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/comments?post=1071"}],"version-history":[{"count":11,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1071\/revisions"}],"predecessor-version":[{"id":9812,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/posts\/1071\/revisions\/9812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media\/1196"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/media?parent=1071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/categories?post=1071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/pt\/blog\/wp-json\/wp\/v2\/tags?post=1071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}