{"id":334,"date":"2021-03-10T03:21:41","date_gmt":"2021-03-10T03:21:41","guid":{"rendered":"https:\/\/turbologo.ru\/blog\/?p=334"},"modified":"2025-09-02T21:13:28","modified_gmt":"2025-09-02T21:13:28","slug":"identita-aziendale","status":"publish","type":"post","link":"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/","title":{"rendered":"Identit\u00e0 aziendale: perch\u00e9 \u00e8 importante"},"content":{"rendered":"\n<p>Oggi, la concorrenza tra le aziende \u00e8 andata ben oltre la rivalit\u00e0 nei volumi di produzione e la corsa tecnologica. Il progresso ha portato le aziende a produrre prodotti quasi identici in aree diverse, che differivano l&#8217;una dall&#8217;altra solo per insignificanti sciocchezze.<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide has-background-dim-80 has-background-dim\"><span class=\"bg-image preload-bg-image lazy-load-bg-img is-loaded is-ready\" data-src=\"https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png\" style=\"background-image: url(&quot;https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png&quot;);\"><\/span><noscript><span class=\"bg-image\" style=\"background-image:url(https:\/\/assets.turbologo.com\/blog\/en\/2021\/05\/07203207\/background.png)\" data-no-lazy=\"true\"><\/span><\/noscript><div class=\"wp-block-cover__inner-container\">\n<p class=\"has-text-align-center has-large-font-size\"><b>Crea il tuo logo con il Turbologo logo maker. <\/b> Ci vogliono meno di 5 minuti e non sono necessarie competenze di progettazione.<\/p>\n<a class=\"button\" href=\"https:\/\/turbologo.com\/it\/crea-logo?utm_source=blog&amp;utm_campaign=article\" style=\"margin-top: 20px; min-width:200px; text-align:center;\">Crea un logo<\/a>\n<\/div><\/div>\n\n\n\n<p>Allora come fanno i produttori a conquistare il cuore dei clienti? L&#8217;identit\u00e0 aziendale \u00e8 la risposta! \u00c8 importante non solo offrire beni o servizi di qualit\u00e0, \u00e8 importante distinguerli sullo sfondo della massa dei concorrenti.<\/p>\n\n\n\n<h2>Cos&#8217;\u00e8 un&#8217;identit\u00e0 aziendale?<\/h2>\n\n\n\n<p>L&#8217;identit\u00e0 aziendale \u00e8 un concetto abbastanza ampio che include un numero considerevole di parti. Quindi, l&#8217;identit\u00e0 aziendale \u00e8 l&#8217;unit\u00e0 degli elementi che identificano l&#8217;affiliazione di tutto ci\u00f2 su cui gli elementi (beni, messaggi di comunicazione, ecc.) Sono posti ad una determinata azienda e la distinguono dai suoi concorrenti.<\/p>\n\n\n\n<p>Inoltre, l&#8217;identit\u00e0 aziendale consente all&#8217;azienda di formare il proprio marchio, essendo un mezzo di formazione dell&#8217;immagine. Riassumendo il risultato provvisorio, da un lato, lo stile dell&#8217;azienda garantisce l&#8217;unit\u00e0 di tutti i beni o servizi prodotti e, dall&#8217;altro, distingue i prodotti da quelli prodotti da aziende concorrenti e li protegge dalla contraffazione.<\/p>\n\n\n\n<p>Come accennato in precedenza, l&#8217;identit\u00e0 aziendale \u00e8 costituita da un insieme di elementi, i principali sono i seguenti:<\/p>\n\n\n\n<ol><li>Marchio. Implica una designazione univoca che consente di personalizzare i prodotti in modo che il consumatore possa distinguerli da prodotti simili di altri produttori.<\/li><li><a href=\"https:\/\/turbologo.com\/it\">Logo<\/a>. Questa \u00e8 una forma di marchio, un simbolo specifico o un&#8217;iscrizione. Oltre a qualsiasi elemento dello stile aziendale, esprime l&#8217;individualit\u00e0 dell&#8217;impresa.<\/li><li>Il blocco aziendale \u00e8 una combinazione di una serie di elementi di stile tradizionali che vengono utilizzati pi\u00f9 spesso.<\/li><li>Slogan aziendale &#8211; una sorta di motto dell&#8217;azienda, che riflette la sua filosofia, gli obiettivi dell&#8217;attivit\u00e0.<\/li><li>Colori di marca. Ogni azienda sceglie il proprio set di colori, che viene utilizzato per <a href=\"https:\/\/turbologo.com\/it\/crea-logo\">creare un logo<\/a>, un marchio, oltre che spesso in qualsiasi modo associato a un tratto caratteristico dell&#8217;azienda.<\/li><li>Il set di caratteri aziendali \u00e8 un modo per visualizzare in modo univoco il testo nei media in stile aziendale dell&#8217;azienda.<\/li><\/ol>\n\n\n\n<p>Mettendo insieme tutte queste parti, l&#8217;azienda inizia a distinguersi dalla concorrenza, attirando nuovi clienti. \u00c8 solo necessario utilizzare correttamente tutto ci\u00f2 che riguarda gli elementi dell&#8217;identit\u00e0 aziendale in una promozione. \u00c8 importante posizionarli correttamente su tutto ci\u00f2 che determina l&#8217;immagine dell&#8217;azienda: prodotti, divise dei dipendenti, veicoli, ecc. Anche l&#8217;identit\u00e0 aziendale deve essere creata in base all&#8217;ambito in cui opera l&#8217;azienda.<\/p>\n\n\n\n<p>Ci sono molti esempi di aziende che hanno fallito a causa della trascuratezza di questa parte importante del business.<\/p>\n\n\n\n<p>Tra le altre cose, lo stile dell&#8217;intera azienda determina in gran parte lo stile del suo leader. Molte aziende di successo lo sono diventate, grazie al carisma della persona che lo guida. Quindi, una volta fu, ad esempio, Steve Jobs, che si innamor\u00f2 degli acquirenti non solo dei prodotti Apple ma anche di se stesso, diventando un idolo per un numero enorme di persone in tutto il mondo. Oggi il mondo \u00e8 conquistato da Ilon Mask, perch\u00e9 non tutti osano trasformare il lancio di un razzo spaziale in uno spettacolo, posizionando l&#8217;auto al posto di un manichino, giusto?<\/p>\n\n\n<div class=\"su-youtube su-u-responsive-media-yes\"><iframe width=\"600\" height=\"400\" src=\"https:\/\/www.youtube.com\/embed\/l-S2Y3SF3mM?\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\n\n\n\n<p>L&#8217;identit\u00e0 aziendale oggi \u00e8 forse il fattore determinante per il successo dell&#8217;azienda sul mercato. Dalla sua corretta formazione dipende da quanto bene l&#8217;azienda interagir\u00e0 con partner e clienti. L&#8217;identit\u00e0 aziendale aumenta i vantaggi competitivi e l&#8217;efficacia della campagna di propaganda. \u00c8 per questi motivi che \u00e8 importante trattare la sua creazione con una responsabilit\u00e0 particolare.<\/p>\n\n\n\n<!-- \u0421\u043a\u0440\u044b\u0442\u0430\u044f \u0441\u0445\u0435\u043c\u0430 \u0434\u043b\u044f \u043f\u043e\u0438\u0441\u043a\u043e\u0432\u0438\u043a\u043e\u0432 --> <script type=\"application\/ld+json\"> { \"@context\": \"https:\/\/schema.org\", \"@type\": \"FAQPage\", \"mainEntity\": [ { \"@type\": \"Question\", \"name\": \"Che cos\\u2019\\u00e8 l\\u2019identit\\u00e0 aziendale?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"L\\u2019insieme coordinato di elementi visivi e verbali che distinguono l\\u2019azienda: logo, colori, tipografia, layout, fotografia\/illustrazioni, tono di voce e regole d\\u2019uso su tutti i canali.\" } }, { \"@type\": \"Question\", \"name\": \"Differenza tra identit\\u00e0 aziendale, brand identity e brand image?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Identit\\u00e0 aziendale\/brand identity = come l\\u2019azienda si presenta (sistema di segni e tono); brand image = come \\u00e8 percepita dal pubblico. La prima \\u00e8 controllabile con linee guida, la seconda \\u00e8 l\\u2019esito percepito.\" } }, { \"@type\": \"Question\", \"name\": \"Quali elementi include un\\u2019identit\\u00e0 aziendale completa?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Logo e varianti, palette colore (RGB\/HEX, CMYK), tipografia, griglie e layout, stile iconografico, fotografia\/illustrazione, pattern, tono di voce, esempi di applicazione (web, social, stampa, packaging, segnaletica).\" } }, { \"@type\": \"Question\", \"name\": \"Come creare l\\u2019identit\\u00e0 aziendale (processo)?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Brief e posizionamento \\u2192 ricerca e benchmark \\u2192 concept visivi\/tonali \\u2192 logo e sistema grafico \\u2192 test (micro\/macro, chiaro\/scuro, accessibilit\\u00e0) \\u2192 brand book e kit file (SVG\/PDF\/EPS, PNG).\" } }, { \"@type\": \"Question\", \"name\": \"Come mantenere coerenza e qualit\\u00e0 nel tempo?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Redigi un brand book con clear space, misure minime, usi corretti\/errati, palette e tipografia approvate, asset per web\/stampa e varianti dark mode\/monocromia. Centralizza gli asset e stabilisci un processo di revisione.\" } } ] } <\/script> <!-- \u041e\u0431\u044b\u0447\u043d\u044b\u0439 \u0442\u0435\u043a\u0441\u0442: h2 + \u0436\u0438\u0440\u043d\u044b\u0435 \u0432\u043e\u043f\u0440\u043e\u0441\u044b --> <h2>Identit\u00e0 aziendale \u2014 Domande frequenti<\/h2> <p><strong>Che cos\u2019\u00e8 l\u2019identit\u00e0 aziendale?<\/strong><\/p> <p>\u00c8 il sistema coordinato di elementi visivi e verbali (logo, colori, font, tono di voce) che distingue l\u2019azienda su tutti i canali.<\/p> <p><strong>Identit\u00e0 vs brand identity vs brand image?<\/strong><\/p> <p>Identit\u00e0\/brand identity = come ti presenti (segni e tono); brand image = come vieni percepito. La prima si progetta e si governa, la seconda \u00e8 il risultato presso il pubblico.<\/p> <p><strong>Cosa include un\u2019identit\u00e0 completa?<\/strong><\/p> <p>Logo e varianti, palette (RGB\/HEX, CMYK), tipografia, griglie\/layout, icone, foto\/illustrazioni, pattern, tono di voce ed esempi per web, social, stampa, packaging e segnaletica.<\/p> <p><strong>Come crearla (processo)?<\/strong><\/p> <p>Brief \u2192 ricerca \u2192 concept \u2192 logo+sistema \u2192 test (micro\/macro, chiaro\/scuro, accessibilit\u00e0) \u2192 brand book e kit file (SVG\/PDF\/EPS, PNG).<\/p> <p><strong>Come mantenerla coerente?<\/strong><\/p> <p>Brand book con clear space, minimi, usi corretti\/errati, palette\/font approvati, asset centralizzati e varianti dark\/mono; prevedi un processo di revisione periodica.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><div class=\"su-heading su-heading-style-default su-heading-align-left\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Other posts<\/div><\/div>\n\n\n<ul class=\"su-posts su-posts-list-loop\">\n<li id=\"su-post-868\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/it\/blog\/clothes-shop-logo\/\">Come creare il logo di un negozio di vestiti<\/a><\/li>\n<li id=\"su-post-1555\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/it\/blog\/los-angeles-clippers-logo\/\">Significato e simbolismo del logo dei Los Angeles Clippers<\/a><\/li>\n<li id=\"su-post-9617\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/it\/blog\/loghi-famosi-in-bianco-e-nero-esempi-di-design-di-logo-e-suggerimenti\/\">Loghi famosi in bianco e nero: Esempi di design di logo e suggerimenti<\/a><\/li>\n<li id=\"su-post-10746\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/it\/blog\/microinfluencer-piccole-imprese-2026\/\">Microinfluencer per piccole imprese nel 2026: come lanciare campagne che generano lead, non solo visualizzazioni<\/a><\/li>\n<li id=\"su-post-9972\" class=\"su-post\"><a href=\"https:\/\/turbologo.com\/it\/blog\/estensioni-di-google-chrome-utili-per-le-aziende\/\">Estensioni di Google Chrome utili per le aziende<\/a><\/li>\n<\/ul>\n\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oggi, la concorrenza tra le aziende \u00e8 andata ben oltre la rivalit\u00e0 nei volumi di produzione e la corsa tecnologica&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Identit\u00e0 aziendale: perch\u00e9 \u00e8 importante | Turbologo<\/title>\n<meta name=\"description\" content=\"Leggi di pi\u00f9 su cos&#039;\u00e8 l&#039;identit\u00e0 aziendale e quale ruolo gioca nel successo del marchio. Ulteriori informazioni sul logo sul blog Turbologo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Identit\u00e0 aziendale: perch\u00e9 \u00e8 importante | Turbologo\" \/>\n<meta property=\"og:description\" content=\"Leggi di pi\u00f9 su cos&#039;\u00e8 l&#039;identit\u00e0 aziendale e quale ruolo gioca nel successo del marchio. Ulteriori informazioni sul logo sul blog Turbologo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/\" \/>\n<meta property=\"og:site_name\" content=\"Logo design e branding - Il blog ufficiale Turbologo\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-10T03:21:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-02T21:13:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.turbologo.com\/blog\/it\/2018\/03\/19133642\/firmenniy-stil-1024x679.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\">\n\t<meta name=\"twitter:data1\" content=\"Ilya Lavrov\">\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data2\" content=\"3 minuti\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#organization\",\"name\":\"Turbologo\",\"url\":\"https:\/\/turbologo.com\/it\/blog\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/turbologo_com\/\",\"https:\/\/www.pinterest.com\/turbologo\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/it\/2020\/03\/19132843\/oFdF5wlUJjw.jpg\",\"width\":500,\"height\":500,\"caption\":\"Turbologo\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#website\",\"url\":\"https:\/\/turbologo.com\/it\/blog\/\",\"name\":\"Logo design e branding - Il blog ufficiale Turbologo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/turbologo.com\/it\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/assets.turbologo.com\/blog\/it\/2018\/03\/19133642\/firmenniy-stil-1024x679.jpg\",\"width\":1024,\"height\":679,\"caption\":\"Esempio di identit\\u00e0 aziendale\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#webpage\",\"url\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/\",\"name\":\"Identit\\u00e0 aziendale: perch\\u00e9 \\u00e8 importante | Turbologo\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#primaryimage\"},\"datePublished\":\"2021-03-10T03:21:41+00:00\",\"dateModified\":\"2025-09-02T21:13:28+00:00\",\"description\":\"Leggi di pi\\u00f9 su cos'\\u00e8 l'identit\\u00e0 aziendale e quale ruolo gioca nel successo del marchio. Ulteriori informazioni sul logo sul blog Turbologo.\",\"breadcrumb\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/\",\"url\":\"https:\/\/turbologo.com\/it\/blog\/\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/\",\"url\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/\",\"name\":\"Identit\\u00e0 aziendale: perch\\u00e9 \\u00e8 importante\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#webpage\"},\"author\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#\/schema\/person\/379800fa881357672b0119e4a2994c17\"},\"headline\":\"Identit\\u00e0 aziendale: perch\\u00e9 \\u00e8 importante\",\"datePublished\":\"2021-03-10T03:21:41+00:00\",\"dateModified\":\"2025-09-02T21:13:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#primaryimage\"},\"articleSection\":\"Marketing\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/turbologo.com\/it\/blog\/identita-aziendale\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#\/schema\/person\/379800fa881357672b0119e4a2994c17\",\"name\":\"Ilya Lavrov\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/turbologo.com\/it\/blog\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/713d4593fdd72be34274409471435888?s=96&d=mm&r=g\",\"caption\":\"Ilya Lavrov\"},\"description\":\"Sono un product e graphic designer con 10 anni di esperienza. Scrittura di branding, creazione di loghi e affari.\",\"sameAs\":[\"http:\/\/ilyalavrov.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/posts\/334"}],"collection":[{"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":12,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"predecessor-version":[{"id":10602,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/posts\/334\/revisions\/10602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/media\/363"}],"wp:attachment":[{"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turbologo.com\/it\/blog\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}